{"id":35300,"date":"2024-01-12T16:13:01","date_gmt":"2024-01-12T19:13:01","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=35300"},"modified":"2024-01-12T16:13:01","modified_gmt":"2024-01-12T19:13:01","slug":"demora-para-atendimento-no-sus-sem-justificativa-e-omissao-do-poder-publico","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2024\/01\/12\/demora-para-atendimento-no-sus-sem-justificativa-e-omissao-do-poder-publico\/","title":{"rendered":"Demora para atendimento no SUS sem justificativa \u00e9 omiss\u00e3o do poder p\u00fablico"},"content":{"rendered":"\n<p>A aus\u00eancia de justificativa para que a administra\u00e7\u00e3o p\u00fablica disponibilize o adequado atendimento equivale a omiss\u00e3o ilegal do ente p\u00fablico, ao deixar de oferecer o direito fundamental \u00e0 sa\u00fade.<\/p>\n\n\n\n<p><img loading=\"lazy\" width=\"300\" height=\"208\" srcset=\"https:\/\/www.conjur.com.br\/wp-content\/uploads\/2024\/01\/closeup-de-um-apoio-de-maos-300x208.jpg 300w, https:\/\/www.conjur.com.br\/wp-content\/uploads\/2024\/01\/closeup-de-um-apoio-de-maos-1024x711.jpg 1024w, https:\/\/www.conjur.com.br\/wp-content\/uploads\/2024\/01\/closeup-de-um-apoio-de-maos-768x533.jpg 768w, https:\/\/www.conjur.com.br\/wp-content\/uploads\/2024\/01\/closeup-de-um-apoio-de-maos-1536x1066.jpg 1536w, https:\/\/www.conjur.com.br\/wp-content\/uploads\/2024\/01\/closeup-de-um-apoio-de-maos-2048x1421.jpg 2048w\" src=\"https:\/\/www.conjur.com.br\/wp-content\/uploads\/2024\/01\/closeup-de-um-apoio-de-maos-300x208.jpg\" alt=\"idosa-hospital-geriatra-geriatria-m\u00e9dico-consulta\"><\/p>\n\n\n\n<p id=\"caption-attachment-736983\">Idosa com cardiopatia ficou um ano e quatro meses na fila do SUS esperando atendimento especializado<\/p>\n\n\n\n<p>Com essa fundamenta\u00e7\u00e3o, o juiz Jos\u00e9 Augusto Reis de Toledo Leite, da Vara da Fazenda P\u00fablica estadual de Atibaia (SP), obrigou o estado de S\u00e3o Paulo a agendar uma consulta m\u00e9dica especializada em neurocirurgia de coluna para uma idosa que aguardou na fila do Sistema \u00danico de Sa\u00fade (SUS) por pelo menos um ano e quatro meses.<\/p>\n\n\n\n<p>A idosa possui v\u00e1rios problemas de sa\u00fade, como cardiopatia, radiculopatia lombar, estenose canal medular e necessita de procedimento cir\u00fargico, segundo o processo. Ela entrou na espera do SUS em abril de 2022.<\/p>\n\n\n\n<p>Em agosto de 2023, a autora apresentou um novo encaminhamento detalhado e assinado por uma m\u00e9dica. O documento denunciava a demora para o agendamento da consulta, mas mesmo assim ela n\u00e3o foi atendida.<\/p><div class=\"nxfpt6a989cc4edf56\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.nxfpt6a989cc4edf56 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.nxfpt6a989cc4edf56 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.nxfpt6a989cc4edf56 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.nxfpt6a989cc4edf56 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.nxfpt6a989cc4edf56 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.nxfpt6a989cc4edf56 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"fhwrw6a989cc4edf3a\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.fhwrw6a989cc4edf3a {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.fhwrw6a989cc4edf3a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.fhwrw6a989cc4edf3a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.fhwrw6a989cc4edf3a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.fhwrw6a989cc4edf3a {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.fhwrw6a989cc4edf3a {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>A defesa alegou que priorizar a consulta m\u00e9dica da mulher em detrimento de outras poderia causar preju\u00edzo a pessoas que tamb\u00e9m necessitam de atendimento na mesma especialidade.<\/p>\n\n\n\n<p>Segundo o juiz, o argumento n\u00e3o se sustenta, uma vez que a idosa n\u00e3o est\u00e1 buscando um privil\u00e9gio, mas sim uma solu\u00e7\u00e3o contra o descaso da administra\u00e7\u00e3o p\u00fablica.<\/p>\n\n\n\n<p>\u201cO direito \u00e0 sa\u00fade e \u00e0 assist\u00eancia aos desamparados encontra previs\u00e3o no art. 6\u00ba da Constitui\u00e7\u00e3o Federal e atende ao princ\u00edpio da dignidade da pessoa humana, conforme prev\u00ea o art. 5\u00ba, \u00a7 1\u00ba, competindo ao Munic\u00edpio, em coopera\u00e7\u00e3o t\u00e9cnica e financeira com a Uni\u00e3o e o Estado, a presta\u00e7\u00e3o de servi\u00e7os que garantam a sa\u00fade da popula\u00e7\u00e3o, sendo pac\u00edfica a obriga\u00e7\u00e3o solid\u00e1ria dos entes p\u00fablicos\u201d, afirma Jos\u00e9 Augusto Toledo.<\/p>\n\n\n\n<p>Sendo assim, o magistrado decidiu que \u00e9 obriga\u00e7\u00e3o do governo de S\u00e3o Paulo agendar a consulta com m\u00e9dico especialista, no prazo de quinze dias contados da intima\u00e7\u00e3o, sob pena de multa di\u00e1ria no valor de R$100,00, limitada ao valor de R$5 mil.<\/p>\n\n\n\n<p><strong>Clique\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.conjur.com.br\/wp-content\/uploads\/2024\/01\/1007040-66.2023.8.26.0048.pdf\" target=\"_blank\">aqui<\/a>\u00a0para ler a decis\u00e3o<\/strong><br><strong>Processo \u00a01007040\u201366.2023.8.26.0048<\/strong><\/p>\n\n\n\n<p>Conjur<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A aus\u00eancia de justificativa para que a administra\u00e7\u00e3o p\u00fablica disponibilize o adequado atendimento equivale a omiss\u00e3o ilegal do ente p\u00fablico, ao deixar de oferecer o direito fundamental \u00e0 sa\u00fade. Idosa com cardiopatia ficou um ano e quatro meses na fila do SUS esperando atendimento especializado Com essa fundamenta\u00e7\u00e3o, o juiz Jos\u00e9 Augusto Reis de Toledo<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2024\/01\/12\/demora-para-atendimento-no-sus-sem-justificativa-e-omissao-do-poder-publico\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35300"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=35300"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35300\/revisions"}],"predecessor-version":[{"id":35301,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35300\/revisions\/35301"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=35300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=35300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=35300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}