{"id":35096,"date":"2023-12-21T15:40:33","date_gmt":"2023-12-21T18:40:33","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=35096"},"modified":"2023-12-21T15:40:33","modified_gmt":"2023-12-21T18:40:33","slug":"cejusc-de-natal-faz-acordo-de-r-25-milhoes-para-vitima-de-acidente-de-trabalho-ocorrido-ha-12-anos","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2023\/12\/21\/cejusc-de-natal-faz-acordo-de-r-25-milhoes-para-vitima-de-acidente-de-trabalho-ocorrido-ha-12-anos\/","title":{"rendered":"Cejusc de Natal faz acordo de R$ 2,5 milh\u00f5es para v\u00edtima de acidente de trabalho ocorrido h\u00e1 12 anos"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img src=\"https:\/\/www.trt21.jus.br\/sites\/default\/files\/styles\/346x231\/public\/2023-12\/site-Cejusc-de-Natal-faz-acordo-de-R%24-2%2C5-milh%C3%B5es-para-v%C3%ADtima-de-acidente-de-trabalho-ocorrido-h%C3%A1-12-anos.jpg?itok=GFDo9Oxj\" alt=\"acidente de trabalho\"\/><\/figure>\n\n\n\n<p>Uma a\u00e7\u00e3o, com mais de 12 anos, envolvendo acidente de trabalho, foi finalizada com uma concilia\u00e7\u00e3o no Cejusc-Natal no valor de R$ 2,5 milh\u00f5es. O trabalhador prestava servi\u00e7o num condom\u00ednio em Natal quando foi v\u00edtima do acidente.<\/p>\n\n\n\n<p>No condom\u00ednio, moram 111 fam\u00edlias, a maioria de baixa renda que, diante da vultosa quantia, n\u00e3o tinham condi\u00e7\u00f5es de pagamento; de outro lado estava o trabalhador com sequelas do acidente e que aguardava h\u00e1 cerca de 12 anos uma solu\u00e7\u00e3o.<\/p>\n\n\n\n<p>Ap\u00f3s quase seis meses de negocia\u00e7\u00e3o, sob a media\u00e7\u00e3o da ju\u00edza coordenadora do Cejusc, Simone Jalil, as partes chegaram a um consenso, com o pagamento \u00e0 parte autora.<\/p>\n\n\n\n<p>No ato de celebra\u00e7\u00e3o do acordo, esteve presente tamb\u00e9m o juiz Alexandre Erico Alves da Silva, titular da 7\u00aa Vara do Trabalho de Natal, de onde o processo se origina, que falou aos presentes sobre a import\u00e2ncia daquele acordo e da concilia\u00e7\u00e3o como solu\u00e7\u00e3o para os conflitos promovendo a pacifica\u00e7\u00e3o social.<\/p>\n\n\n\n<p>Os advogados de ambas as partes enalteceram a atua\u00e7\u00e3o do Cejusc declarando que ali se resolvia n\u00e3o apenas um processo, mas uma quest\u00e3o social; que a paz que se trazia naquele momento \u00e0 parte autora e aos cond\u00f4minos era algo incalcul\u00e1vel. Uma cond\u00f4mina presente ressaltou que &#8220;sa\u00eda dali com outra vis\u00e3o da Justi\u00e7a; que n\u00e3o imaginava algo t\u00e3o pr\u00f3ximo e de tanta aten\u00e7\u00e3o ao cidad\u00e3o.&#8221;<\/p><div class=\"aybkh6a04c215a6029\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.aybkh6a04c215a6029 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.aybkh6a04c215a6029 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.aybkh6a04c215a6029 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.aybkh6a04c215a6029 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.aybkh6a04c215a6029 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.aybkh6a04c215a6029 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"amqtj6a04c215a6005\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.amqtj6a04c215a6005 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.amqtj6a04c215a6005 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.amqtj6a04c215a6005 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.amqtj6a04c215a6005 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.amqtj6a04c215a6005 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.amqtj6a04c215a6005 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>\u201cEsse \u00e9 o verdadeiro objetivo da concilia\u00e7\u00e3o\u201d, destacou a Ju\u00edza Coordenadora Simone Jalil. \u201cN\u00e3o se trata de jogo de valores, mas de resolver conflitos; dirimir quest\u00f5es. Hoje tivemos uma solu\u00e7\u00e3o encontrada pelas partes ap\u00f3s longas conversas. Ambas as partes sa\u00edram daqui felizes e se cumprimentando\u201d.<\/p>\n\n\n\n<p>\u201cHoje esse conflito foi realmente pacificado. Ficamos muito felizes com mais uma solu\u00e7\u00e3o encontrada pelo nosso Cejusc\u201d, concluiu ela.<\/p>\n\n\n\n<p>O processo \u00e9 o 0069200-49.2012.5.21.0007<\/p>\n\n\n\n<p>Fonte: CCS TRT-RN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma a\u00e7\u00e3o, com mais de 12 anos, envolvendo acidente de trabalho, foi finalizada com uma concilia\u00e7\u00e3o no Cejusc-Natal no valor de R$ 2,5 milh\u00f5es. O trabalhador prestava servi\u00e7o num condom\u00ednio em Natal quando foi v\u00edtima do acidente. No condom\u00ednio, moram 111 fam\u00edlias, a maioria de baixa renda que, diante da vultosa quantia, n\u00e3o tinham condi\u00e7\u00f5es<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2023\/12\/21\/cejusc-de-natal-faz-acordo-de-r-25-milhoes-para-vitima-de-acidente-de-trabalho-ocorrido-ha-12-anos\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35096"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=35096"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35096\/revisions"}],"predecessor-version":[{"id":35097,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35096\/revisions\/35097"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=35096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=35096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=35096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}