{"id":35089,"date":"2023-12-21T10:09:47","date_gmt":"2023-12-21T13:09:47","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=35089"},"modified":"2023-12-21T10:09:47","modified_gmt":"2023-12-21T13:09:47","slug":"barroso-deve-pautar-julgamentos-sobre-drogas-e-aborto-para-o-ano-que-vem","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2023\/12\/21\/barroso-deve-pautar-julgamentos-sobre-drogas-e-aborto-para-o-ano-que-vem\/","title":{"rendered":"Barroso deve pautar julgamentos sobre drogas e aborto para o ano que vem"},"content":{"rendered":"\n<p>O presidente do Supremo Tribunal Federal, ministro Lu\u00eds Roberto Barroso, disse nesta quarta-feira (20\/12) que deve elaborar a pauta de julgamentos do Plen\u00e1rio para 2024 at\u00e9 o fim deste ano. As sess\u00f5es colegiadas ser\u00e3o reiniciadas em fevereiro e devem retomar julgamentos de processos iniciados em 2023.<img loading=\"lazy\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.conjur.com.br\/wp-content\/uploads\/2023\/07\/luis-roberto-barroso-20232-300x200.jpeg 300w, https:\/\/www.conjur.com.br\/wp-content\/uploads\/2023\/07\/luis-roberto-barroso-20232-768x512.jpeg 768w, https:\/\/www.conjur.com.br\/wp-content\/uploads\/2023\/07\/luis-roberto-barroso-20232-150x100.jpeg 150w, https:\/\/www.conjur.com.br\/wp-content\/uploads\/2023\/07\/luis-roberto-barroso-20232.jpeg 799w\" src=\"https:\/\/www.conjur.com.br\/wp-content\/uploads\/2023\/07\/luis-roberto-barroso-20232-300x200.jpeg\" alt=\"\"><\/p>\n\n\n\n<p id=\"caption-attachment-715474\">Barroso afirmou que n\u00e3o existe tema tabu para a pauta do Supremo<\/p>\n\n\n\n<p>Um dos assuntos a serem retomados \u00e9 a a\u00e7\u00e3o que discute a defini\u00e7\u00e3o do que seja a quantidade para consumo pr\u00f3prio de drogas. De acordo com Barroso, \u00e9 preciso deixar claro que o Supremo n\u00e3o est\u00e1 descriminalizando a maconha, pois isso j\u00e1 foi feito pelo Poder Legislativo. \u201cO que temos discutido aqui, que tamb\u00e9m \u00e9 uma discuss\u00e3o mal compreendida, \u00e9 qual a quantidade de maconha que distingue o usu\u00e1rio do traficante. Se o Supremo n\u00e3o definir isso, quem far\u00e1 \u00e9 o policial no momento do flagrante. N\u00e3o h\u00e1 solu\u00e7\u00e3o f\u00e1cil para lidar com as drogas no mundo inteiro. Esse \u00e9 um problema que deve ser enfrentado, mas o que posso dizer \u00e9 que a pol\u00edtica p\u00fablica que praticamos no Brasil n\u00e3o funciona.\u201d<\/p>\n\n\n\n<p>Quanto \u00e0 a\u00e7\u00e3o que discute a descriminaliza\u00e7\u00e3o do aborto, o presidente do STF disse que n\u00e3o h\u00e1 tema tabu para a pauta. \u201cPenso que o debate na sociedade brasileira ainda n\u00e3o est\u00e1 amadurecido. E as pessoas n\u00e3o t\u00eam a exata consci\u00eancia do que est\u00e1 sendo discutido. \u00c9 preciso fazer um debate esclarecido, a discuss\u00e3o que se coloca \u00e9 saber se a mulher que teve o infort\u00fanio de fazer um aborto deve ser presa, que \u00e9 a consequ\u00eancia da criminaliza\u00e7\u00e3o\u201d.<\/p><div class=\"dliug6a04c1f252df9\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.dliug6a04c1f252df9 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.dliug6a04c1f252df9 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.dliug6a04c1f252df9 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.dliug6a04c1f252df9 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.dliug6a04c1f252df9 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.dliug6a04c1f252df9 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"jokgq6a04c1f252ddb\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.jokgq6a04c1f252ddb {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.jokgq6a04c1f252ddb {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.jokgq6a04c1f252ddb {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.jokgq6a04c1f252ddb {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.jokgq6a04c1f252ddb {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.jokgq6a04c1f252ddb {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O presidente do Supremo participou nesta quarta, no Congresso Nacional, do evento de promulga\u00e7\u00e3o da Emenda Constitucional 123\/2023, que promove a reforma tribut\u00e1ria. \u201cEssa reforma ter\u00e1 um impacto muito grande sobre o Poder Judici\u00e1rio. Tenho a expectativa de que ela possa diminuir a litigiosidade tribut\u00e1ria no Brasil, que traz muita imprevisibilidade para as contas do governo e das empresas de uma maneira geral.\u201d<\/p>\n\n\n\n<p>Para ele, a reforma deve avan\u00e7ar mais. \u201cEssa foi a primeira parte da reforma, que \u00e9 de simplifica\u00e7\u00e3o. Agora o desafio \u00e9 fazer com que o sistema seja mais justo. A base da arrecada\u00e7\u00e3o est\u00e1 na tributa\u00e7\u00e3o sobre o consumo, em que todas as pessoas pagam o mesmo. Os modelos de justi\u00e7a social envolvem a tributa\u00e7\u00e3o\u00a0direta\u201d.<\/p>\n\n\n\n<p>Conjur<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente do Supremo Tribunal Federal, ministro Lu\u00eds Roberto Barroso, disse nesta quarta-feira (20\/12) que deve elaborar a pauta de julgamentos do Plen\u00e1rio para 2024 at\u00e9 o fim deste ano. As sess\u00f5es colegiadas ser\u00e3o reiniciadas em fevereiro e devem retomar julgamentos de processos iniciados em 2023. Barroso afirmou que n\u00e3o existe tema tabu para a<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2023\/12\/21\/barroso-deve-pautar-julgamentos-sobre-drogas-e-aborto-para-o-ano-que-vem\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35089"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=35089"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35089\/revisions"}],"predecessor-version":[{"id":35090,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35089\/revisions\/35090"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=35089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=35089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=35089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}