{"id":35069,"date":"2023-12-19T16:06:32","date_gmt":"2023-12-19T19:06:32","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=35069"},"modified":"2023-12-19T16:06:32","modified_gmt":"2023-12-19T19:06:32","slug":"despedida-colegas-de-pleno-lembram-trajetoria-do-desembargador-gilson-barbosa-em-sua-ultima-sessao-no-tj","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2023\/12\/19\/despedida-colegas-de-pleno-lembram-trajetoria-do-desembargador-gilson-barbosa-em-sua-ultima-sessao-no-tj\/","title":{"rendered":"DESPEDIDA: Colegas de Pleno lembram trajet\u00f3ria do desembargador Gilson Barbosa em sua \u00faltima sess\u00e3o no TJ"},"content":{"rendered":"\n<p>A \u00faltima sess\u00e3o do ano do Pleno do Tribunal de Justi\u00e7a do RN, em 2023, marcou oficialmente a despedida do desembargador Gilson Barbosa, que se aposenta compulsoriamente do servi\u00e7o p\u00fablico ao completar 75 anos. Nesta ter\u00e7a-feira (19\/12), o magistrado deixa a Corte de Justi\u00e7a potiguar ap\u00f3s 41 dedicados \u00e0 magistratura. O nome do magistrado foi escolhido, \u00e0 unanimidade, pelo Pleno do TJRN, pelo crit\u00e9rio de antiguidade. A posse no cargo de desembargador do Tribunal de Justi\u00e7a potiguar ocorreu em 29 de agosto de 2013.<\/p>\n\n\n\n<p>A sess\u00e3o foi marcada por homenagens dos demais colegas do Plen\u00e1rio e amigos. Foi exibido um document\u00e1rio produzido pela Secretaria de Comunica\u00e7\u00e3o Social do TJRN sobre sua trajet\u00f3ria, com depoimentos de magistrados, familiares e auxiliares e amigos do desembargador Gilson Barbosa.<\/p>\n\n\n\n<p>O presidente do TJRN, desembargador Am\u00edlcar Maia, foi o primeiro a falar sobre o corregedor-geral de Justi\u00e7a, cargo no qual ele se despede da magistratura potiguar. &#8220;Todos que passam pelo Tribunal deixam a sua marca e contribui\u00e7\u00e3o. E o desembargador Gilson \u00e9 um magistrado que dedicou mais da metade da sua vida ao Judici\u00e1rio, ele chega aos 75 anos de idade e aos 41 de magistratura. Vossa Excel\u00eancia foi um grande amigo, partilhamos muitos desafios\u201d, ressaltou Am\u00edlcar Maia.<\/p>\n\n\n\n<p>\u201cConhe\u00e7o Vossa Excel\u00eancia desde quando era juiz em Martins e eu acad\u00eamico de Direito. Lembro da sua paix\u00e3o pelos livros, do perfeccionismo, e de uma coisa que hoje o jurisdicionado tem buscado que \u00e9 o juiz presente na comarca. Agrade\u00e7o, em nome de toda a Corte, a sua dedica\u00e7\u00e3o&#8221;, disse o presidente do TJRN.<\/p>\n\n\n\n<p>O vice-presidente do Tribunal, desembargador Glauber R\u00eago, destacou tr\u00eas pontos que considera importantes na trajet\u00f3ria do desembargador Gilson. &#8220;O primeiro \u00e9 a longevidade, que Vossa Excel\u00eancia tem e ainda ter\u00e1 por mais tempo. A outra, \u00e9 a quest\u00e3o do dever cumprido. Vossa Excel\u00eancia certamente tem a satisfa\u00e7\u00e3o de, nesses mais de 40 anos de magistratura, de ter realizado o seu melhor. E o terceiro \u00e9 o seu legado. Tive o privil\u00e9gio de conviver nessa ultima d\u00e9cada na C\u00e2mara Criminal e o exemplo que Vossa Excel\u00eancia deixa \u00e9 muito destacado&#8221;, enumerou Glauber R\u00eago.<\/p><div class=\"ofzwg6a04c1f1cc137\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ofzwg6a04c1f1cc137 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ofzwg6a04c1f1cc137 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ofzwg6a04c1f1cc137 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ofzwg6a04c1f1cc137 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ofzwg6a04c1f1cc137 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ofzwg6a04c1f1cc137 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"qervu6a04c1f1cc11a\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.qervu6a04c1f1cc11a {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.qervu6a04c1f1cc11a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.qervu6a04c1f1cc11a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.qervu6a04c1f1cc11a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.qervu6a04c1f1cc11a {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.qervu6a04c1f1cc11a {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/12\/prlzeehhqg-dsc0064-1024x683.jpeg\" alt=\"\" class=\"wp-image-35070\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/12\/prlzeehhqg-dsc0064-1024x683.jpeg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/12\/prlzeehhqg-dsc0064-300x200.jpeg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/12\/prlzeehhqg-dsc0064-768x512.jpeg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/12\/prlzeehhqg-dsc0064-1536x1025.jpeg 1536w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/12\/prlzeehhqg-dsc0064-2048x1367.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>Magistrados, advogados, ex-colegas de trabalho homenagearam o corregedor-geral de Justi\u00e7a em sua despedida da Corte potiguar<\/p>\n\n\n\n<p><strong>Mais homenagens<\/strong><\/p>\n\n\n\n<p>A procuradora-geral de Justi\u00e7a, Elaine Cardoso, tamb\u00e9m agradeceu ao desembargador Gilson Barbosa. &#8220;Quero externar nossa admira\u00e7\u00e3o, nosso reconhecimento a toda essa trajet\u00f3ria de mais de 40 anos dedicados \u00e0 magistratura e \u00e0 sociedade potiguar. Com muita responsabilidade, senso de Justi\u00e7a, esp\u00edrito p\u00fablico, mas tamb\u00e9m sempre com a disponibilidade de ouvir, com acolhimento. Isso, certamente, o senhor levar\u00e1 para toda a vida. Em meu nome e do Minist\u00e9rio P\u00fablico desejo feliz vida nova&#8221;, ressaltou Cardoso.<\/p>\n\n\n\n<p>O presidente da Ordem dos Advogados do Brasil Seccional do Rio Grande do Norte (OAB-RN), Aldo Medeiros tamb\u00e9m homenageou o desembargador Gilson. &#8220;Estou aqui representado a advocacia do Rio grande do Norte para dizer o quanto o senhor honrou a magistratura que exerceu por mais de 40 anos. \u00e9 importante que se destaque a seriedade e a modera\u00e7\u00e3o com as quase o senhor julgou os seus processos. E o respeito que o senhor adquiriu com essa atitude de absoluta isen\u00e7\u00e3o e de aplica\u00e7\u00e3o da Justi\u00e7a. Destaco, principalmente, o per\u00edodo que Vossa Excel\u00eancia presidiu o TRE-RN. Foram anos muito dif\u00edceis, de ataque \u00e0 Justi\u00e7a Federal jamais recebidos. E a Justi\u00e7a Eleitoral do RN passou absolutamente inc\u00f3lume diante de sua lideran\u00e7a\u201d.<\/p>\n\n\n\n<p>O presidente da Associa\u00e7\u00e3o dos Magistrados do RN, juiz Andreo Marques, tamb\u00e9m homenageou o desembargador Gilson. &#8220;A AMARN n\u00e3o poderia deixar de reconhecer o seu trabalho dedicado \u00e0 magistratura. Gostaria de destacar a independ\u00eancia, a serenidade, a seriedade e a fidalguia com as quais sempre nos tratou&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A \u00faltima sess\u00e3o do ano do Pleno do Tribunal de Justi\u00e7a do RN, em 2023, marcou oficialmente a despedida do desembargador Gilson Barbosa, que se aposenta compulsoriamente do servi\u00e7o p\u00fablico ao completar 75 anos. Nesta ter\u00e7a-feira (19\/12), o magistrado deixa a Corte de Justi\u00e7a potiguar ap\u00f3s 41 dedicados \u00e0 magistratura. O nome do magistrado foi<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2023\/12\/19\/despedida-colegas-de-pleno-lembram-trajetoria-do-desembargador-gilson-barbosa-em-sua-ultima-sessao-no-tj\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35069"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=35069"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35069\/revisions"}],"predecessor-version":[{"id":35071,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35069\/revisions\/35071"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=35069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=35069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=35069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}