{"id":3119,"date":"2019-10-15T11:37:20","date_gmt":"2019-10-15T14:37:20","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=3119"},"modified":"2019-10-15T11:37:20","modified_gmt":"2019-10-15T14:37:20","slug":"decreto-estabelece-regras-para-o-trabalho-temporario","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2019\/10\/15\/decreto-estabelece-regras-para-o-trabalho-temporario\/","title":{"rendered":"Decreto estabelece regras para o trabalho tempor\u00e1rio"},"content":{"rendered":"\n<p>Foi publicado no DOU desta ter\u00e7a-feira, 15, o decreto&nbsp;<a href=\"https:\/\/migalhas.com.br\/arquivos\/2019\/10\/art20191015-02.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">10.060\/19<\/a>, que regulamenta o trabalho tempor\u00e1rio. A norma regulamenta dispositivo da lei&nbsp;<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/L6019compilado.htm\" target=\"_blank\" rel=\"noreferrer noopener\">6.019\/1974<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/www.globalframe.com.br\/gf_base\/empresas\/MIGA\/imagens\/992E54D3690B228F6E6554E0C806FC575787_trabalho.png\" alt=\"t\"\/><\/figure>\n\n\n\n<p>Trabalho tempor\u00e1rio, segundo o decreto, \u00e9 aquele prestado por pessoa f\u00edsica contratada por uma empresa de trabalho tempor\u00e1rio que a coloca \u00e0 disposi\u00e7\u00e3o de uma empresa tomadora de servi\u00e7os ou cliente, para atender \u00e0 necessidade de substitui\u00e7\u00e3o transit\u00f3ria de pessoal permanente ou \u00e0 demanda complementar de servi\u00e7os.<\/p>\n\n\n\n<p>De acordo com a norma, ao trabalhador tempor\u00e1rio est\u00e3o assegurados direitos como remunera\u00e7\u00e3o equivalente \u00e0quela recebida pelos empregados da mesma categoria da empresa tomadora de servi\u00e7os ou cliente; pagamento de f\u00e9rias proporcionais; FGTS; benef\u00edcios e servi\u00e7os da Previd\u00eancia Social e seguro de acidente do trabalho.<\/p>\n\n\n\n<p>O texto prev\u00ea que a jornada de trabalho ser\u00e1 de, no m\u00e1ximo, 8 horas di\u00e1rias, podendo ter dura\u00e7\u00e3o estendida caso a empresa tomadora de servi\u00e7os utilize jornada de trabalho espec\u00edfica.<\/p><div class=\"vekjo6a04724b73ac4\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.vekjo6a04724b73ac4 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.vekjo6a04724b73ac4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vekjo6a04724b73ac4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vekjo6a04724b73ac4 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vekjo6a04724b73ac4 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vekjo6a04724b73ac4 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"xveiv6a04724b73aa5\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.xveiv6a04724b73aa5 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.xveiv6a04724b73aa5 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.xveiv6a04724b73aa5 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.xveiv6a04724b73aa5 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.xveiv6a04724b73aa5 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.xveiv6a04724b73aa5 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>As horas que excedem a jornada normal de trabalho ser\u00e3o remuneradas com acr\u00e9scimo de, no m\u00ednimo, 50%, dever\u00e1 ter acrescido, no m\u00ednimo, 20% de sua remunera\u00e7\u00e3o quando trabalhar no per\u00edodo noturno.<\/p>\n\n\n\n<p>A empresa prestadora de trabalho tempor\u00e1rio ficar\u00e1 obrigada a apresentar, quando solicitado, o contrato celebrado com o trabalhador tempor\u00e1rio, a comprova\u00e7\u00e3o do recolhimento das contribui\u00e7\u00f5es previdenci\u00e1rias e os demais documentos comprobat\u00f3rios do cumprimento das obriga\u00e7\u00f5es estabelecidas pelo decreto que regulamenta a atividade.<\/p>\n\n\n\n<p><strong>Migalhas<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O texto prev\u00ea que a jornada de trabalho ser\u00e1 de, no m\u00e1ximo, 8 horas di\u00e1rias, podendo ter dura\u00e7\u00e3o estendida caso a empresa tomadora de servi\u00e7os utilize jornada de trabalho espec\u00edfica.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2019\/10\/15\/decreto-estabelece-regras-para-o-trabalho-temporario\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3119"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3119"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3119\/revisions"}],"predecessor-version":[{"id":3120,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3119\/revisions\/3120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/473"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}