{"id":2908,"date":"2019-10-07T20:21:53","date_gmt":"2019-10-07T23:21:53","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=2908"},"modified":"2019-10-07T20:21:53","modified_gmt":"2019-10-07T23:21:53","slug":"madrasta-padrasto-pode-postar-foto-com-meu-filho-nas-redes-sociais","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2019\/10\/07\/madrasta-padrasto-pode-postar-foto-com-meu-filho-nas-redes-sociais\/","title":{"rendered":"Madrasta\/Padrasto pode postar foto com meu filho nas redes sociais?"},"content":{"rendered":"\n<p>Diariamente recebo mensagens do tipo:<\/p>\n\n\n\n<p>\u201cA madrasta do meu filho posta foto com ele nas redes sociais sem minha autoriza\u00e7\u00e3o, o que posso fazer para proibir?\u201d<\/p>\n\n\n\n<p>\u201cPoso proibir a madrasta de postar foto com meu filho no Facebook?\u201d<\/p>\n\n\n\n<p>\u201cN\u00e3o quero a madrasta postando foto do meu filho no Instagram, o que fazer?\u201d<\/p>\n\n\n\n<p>\u201cPosso proibir meus filhos de tirarem foto com a madrasta?\u201d<\/p>\n\n\n\n<p>\u201cA madrasta do meu filho tem colocado foto dele nas redes sociais dela, o que posso fazer?\u201d<\/p>\n\n\n\n<p>E afinal, a madrasta e o padrasto podem ou n\u00e3o podem postar fotos dos enteados em suas redes sociais?<\/p>\n\n\n\n<p>Para que voc\u00ea entenda como lidar com essa situa\u00e7\u00e3o \u00e9 importante voc\u00ea entender 6 (seis) coisas:<\/p>\n\n\n\n<h3>1. Direito do filho \u00e0 Liberdade<\/h3>\n\n\n\n<p>O&nbsp;<a href=\"https:\/\/www.jusbrasil.com.br\/legislacao\/91764\/estatuto-da-crian%C3%A7a-e-do-adolescente-lei-8069-90\">Estatuto da Crian\u00e7a e do Adolescente<\/a>&nbsp;(Lei&nbsp;<a href=\"https:\/\/www.jusbrasil.com.br\/legislacao\/91764\/estatuto-da-crian%C3%A7a-e-do-adolescente-lei-8069-90\">8.069<\/a>) prev\u00ea que a crian\u00e7a e o adolescente t\u00eam direito \u00e0 liberdade (art.&nbsp;<a href=\"https:\/\/www.jusbrasil.com.br\/topicos\/10618478\/artigo-15-da-lei-n-8069-de-13-de-julho-de-1990\">15<\/a>&nbsp;<a href=\"https:\/\/www.jusbrasil.com.br\/legislacao\/91764\/estatuto-da-crian%C3%A7a-e-do-adolescente-lei-8069-90\">ECA<\/a>) e entende que participar da vida familiar e comunit\u00e1ria, sem discrimina\u00e7\u00e3o (artigo 16 inciso V) faz parte da liberdade do menor!<\/p>\n\n\n\n<p>Mas a\u00ed voc\u00ea pode me perguntar: \u201cE madrasta\/padrasto \u00e9 familiar?\u201d<\/p>\n\n\n\n<h3>2. Madrasta\/Padrasto \u00e9 parente<\/h3>\n\n\n\n<p>O nosso&nbsp;<a href=\"https:\/\/www.jusbrasil.com.br\/legislacao\/1035419\/c%C3%B3digo-civil-lei-10406-02\">C\u00f3digo Civil<\/a>&nbsp;(Lei&nbsp;<a href=\"https:\/\/www.jusbrasil.com.br\/legislacao\/1035419\/c%C3%B3digo-civil-lei-10406-02\">10.406<\/a>) diz que cada c\u00f4njuge ou companheiro \u00e9 aliado aos parentes do outro pelo v\u00ednculo da afinidade (art. 1.595). Logo a madrasta\/padrasto \u00e9 parente por afinidade do enteado.<\/p>\n\n\n\n<p>Isso n\u00e3o quer dizer que eles tenham os mesmos direitos que pai e m\u00e3e, mas isso \u00e9 assunto para outro artigo.<\/p>\n\n\n\n<p>Aqui vamos nos ater ao fato de que madrasta\/padrasto \u00e9 parente por afinidade dos seus filhos.<\/p>\n\n\n\n<h3>3. Direito de Imagem dos filhos<\/h3>\n\n\n\n<p>A&nbsp;<a href=\"https:\/\/www.jusbrasil.com.br\/legislacao\/188546065\/constitui%C3%A7%C3%A3o-federal-constitui%C3%A7%C3%A3o-da-republica-federativa-do-brasil-1988\">Constitui\u00e7\u00e3o Federal<\/a>&nbsp;tem o Direito \u00e0 imagem como inviol\u00e1vel (art. 5\u00ba inciso X) e assegura indeniza\u00e7\u00e3o pelo dano moral e material decorrido pela sua viola\u00e7\u00e3o.<\/p>\n\n\n\n<p>Vale esclarecer que o direito \u00e0 imagem inclui dois direitos aut\u00f4nomos e distintos: por um lado o direito a n\u00e3o ser fotografado\/filmado e, por outro lado, o direito a que a fotografia\/v\u00eddeo n\u00e3o seja publicada.<\/p>\n\n\n\n<p>O&nbsp;<a href=\"https:\/\/www.jusbrasil.com.br\/legislacao\/1035419\/c%C3%B3digo-civil-lei-10406-02\">C\u00f3digo Civil<\/a>&nbsp;(art. 20) prev\u00ea que a exposi\u00e7\u00e3o ou a utiliza\u00e7\u00e3o da imagem de uma pessoa poder\u00e3o ser proibidas, a seu requerimento e sem preju\u00edzo da indeniza\u00e7\u00e3o que couber, se lhe atingirem a honra, a boa fama ou a respeitabilidade, ou se se destinarem a fins comerciais, logo, se faz necess\u00e1ria autoriza\u00e7\u00e3o para divulga\u00e7\u00e3o de imagem (salvo se necess\u00e1rias \u00e0 administra\u00e7\u00e3o da justi\u00e7a ou \u00e0 manuten\u00e7\u00e3o da ordem p\u00fablica).<\/p>\n\n\n\n<p>O&nbsp;<a href=\"https:\/\/www.jusbrasil.com.br\/legislacao\/91764\/estatuto-da-crian%C3%A7a-e-do-adolescente-lei-8069-90\">Estatuto da Crian\u00e7a e do Adolescente<\/a>&nbsp;estabelece (art. 17) o Direito ao respeito ao menor e entende que esse direito abrange a preserva\u00e7\u00e3o da imagem.<\/p>\n\n\n\n<p>Assim n\u00e3o resta d\u00favida de que a imagem da crian\u00e7a deve ser preservada, mas isso significa que n\u00e3o se pode divulgar foto e v\u00eddeo de crian\u00e7a e adolescente em nenhuma hip\u00f3tese?<\/p>\n\n\n\n<h3>4. Tipos de fotos\/v\u00eddeo de crian\u00e7a e adolescente proibidos<\/h3>\n\n\n\n<p>Os tipo de imagem que n\u00e3o devem ser divulgadas s\u00e3o:<\/p>\n\n\n\n<p>a) Cena onde o menor est\u00e1 em situa\u00e7\u00e3o desumana, violenta, aterrorizante, vexat\u00f3ria ou constrangedora; (art. 18)<\/p>\n\n\n\n<p>b) Cena que exponha situa\u00e7\u00e3o que humilhe; ou ameace gravemente; ridicularize a crian\u00e7a ou adolescente;<\/p>\n\n\n\n<p>c) Exponha \u00e0 crian\u00e7a \u00e0 risco,<\/p>\n\n\n\n<p>d) Fotos contendo nudez;<\/p>\n\n\n\n<p>e) Cena de sexo expl\u00edcito ou pornogr\u00e1fica, envolvendo crian\u00e7a ou adolescente.<\/p>\n\n\n\n<p>De maneira pr\u00e1tica foto onde aparece a escola ou uniforme do menor; bem como demonstra sua rotina, pode expor a crian\u00e7a ou adolescente \u00e0 risco. Isso porque \u00e9 sabido que muitos predadores sexuais e ped\u00f3filos usam essas redes para melhor atingirem os seus intentos. Ent\u00e3o esse tipo de divulga\u00e7\u00e3o de imagem exp\u00f5e o menor \u00e0 risco.<\/p><div class=\"msofi6a04e9c41f493\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.msofi6a04e9c41f493 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.msofi6a04e9c41f493 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.msofi6a04e9c41f493 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.msofi6a04e9c41f493 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.msofi6a04e9c41f493 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.msofi6a04e9c41f493 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"vzrah6a04e9c41f478\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.vzrah6a04e9c41f478 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.vzrah6a04e9c41f478 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vzrah6a04e9c41f478 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vzrah6a04e9c41f478 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vzrah6a04e9c41f478 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vzrah6a04e9c41f478 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<h3>5. Tipos de foto\/v\u00eddeo de crian\u00e7a ou adolescente permitidos<\/h3>\n\n\n\n<p>Aqui vale enfatizar que na verdade, os filhos n\u00e3o s\u00e3o coisas ou objetos pertencentes aos pais e de que estes podem dispor a seu belo prazer. S\u00e3o pessoas e consequentemente titulares de direitos.<\/p>\n\n\n\n<p>Cabe \u00e0 crian\u00e7a ou adolescente que j\u00e1 consegue se expressar e se manifestar escolher se quer tirar ou n\u00e3o foto e divulg\u00e1-la.<\/p>\n\n\n\n<p>N\u00e3o h\u00e1 veda\u00e7\u00e3o para fotos que demonstre afeto, relacionamento familiar cotidiano, passeio, realiza\u00e7\u00f5es do menor; estes s\u00e3o apenas alguns exemplos.<\/p>\n\n\n\n<h3>6. Dicas de Seguran\u00e7a<\/h3>\n\n\n\n<p>Cuidado! Postar uma foto ou v\u00eddeo de uma crian\u00e7a ou adolescente pode coloc\u00e1-lo em risco. Por isso separei 7 dicas para te ajudar a proteger seu filho quando voc\u00ea for divulgar foto dele:<\/p>\n\n\n\n<p>a) Evite ou n\u00e3o divulgue fotos recentes com uniforme da escola ou outras refer\u00eancias que ajude a identificar locais que seu filho frequenta.<\/p>\n\n\n\n<p>b) N\u00e3o poste fotos dos amigos do seu filho, sem permiss\u00e3o dos outros pais.<\/p>\n\n\n\n<p>c) N\u00e3o poste fotos dos seus filhos com objetos de valor da fam\u00edlia, como carro, j\u00f3ias, itens tecnol\u00f3gicos, etc.<\/p>\n\n\n\n<p>d) Cuidado com fotos em alta resolu\u00e7\u00e3o \u2014 evite! Isso facilita a manipula\u00e7\u00e3o das fotos por outras pessoas para fins desconhecidos.<\/p>\n\n\n\n<p>e) Evite divulgar a localiza\u00e7\u00e3o de lugares que voc\u00ea frequenta como: seu trabalho, academia, restaurantes, parquinhos, etc.<\/p>\n\n\n\n<p>f) Quando for divulgar foto do seu filho prefira configurar para que seja compartilhada de maneira privada somente pelos seus \u201camigos\u201d. Evite compartilhar em modo p\u00fablico.<\/p>\n\n\n\n<p>g) Restrinja o compartilhamento de foto<\/p>\n\n\n\n<h3>Curiosidade<\/h3>\n\n\n\n<p>O Tribunal da Rela\u00e7\u00e3o de \u00c9vora, um Tribunal Superior Portugu\u00eas, competente para julgar,&nbsp;<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"http:\/\/www.dgsi.pt\/jtre.nsf\/134973db04f39bf2802579bf005f080b\/7c52769f1dfab8be80257e830052d374?OpenDocument&amp;Highlight=0,redes,sociais\">recurso (2\u00aa inst\u00e2ncia)<\/a>&nbsp;decidiu proibir pai e m\u00e3e de divulgarem a imagem e informa\u00e7\u00f5es que permitem a identifica\u00e7\u00e3o da filha de 12 anos em redes sociais por entenderem que preservariam o direito \u00e0 intimidade da vida privada e da prote\u00e7\u00e3o dos dados pessoais e, sobretudo, da seguran\u00e7a no cyberespa\u00e7o.<\/p>\n\n\n\n<p>E o Tribunal da Rela\u00e7\u00e3o do Porto, outro Tribunal Superior Portugu\u00eas, entende que publicar foto em rede social sem consentimento \u00e9 crime, mesmo que o fotografado tenha permitido tirar a foto!<\/p>\n\n\n\n<p>A decis\u00e3o consta de um&nbsp;<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"http:\/\/www.dgsi.pt\/jtrp.nsf\/56a6e7121657f91e80257cda00381fdf\/94f97edeaa596d8f80257e6f004fbde7?OpenDocument&amp;Highlight=0,facebook\">ac\u00f3rd\u00e3o&nbsp;<\/a>que analisou um caso onde um homem reclamou das fotos publicadas no Facebook sem seu consentimento por sua amante com quem se relacionou por 1 ano, e apesar de terem uma filha, o caso amoroso era absolutamente sigiloso.<\/p>\n\n\n\n<p>O judici\u00e1rio brasileiro entende pela condena\u00e7\u00e3o para indenizar por danos morais quando h\u00e1 divulga\u00e7\u00e3o de imagem (foto ou v\u00eddeo) com cond\u00e3o de ofender a honra e a imagem daquele que est\u00e1 na foto\/v\u00eddeo.<\/p>\n\n\n\n<p>O STJ, no julgamento do Recurso Especial n\u00ba 1.650.725\/MG, decidiu que, &#8220;ao disponibilizarem informa\u00e7\u00f5es, opini\u00f5es e coment\u00e1rios nas redes sociais na internet, os usu\u00e1rios se tornam os respons\u00e1veis principais e imediatos pelas consequ\u00eancias da livre manifesta\u00e7\u00e3o de seu pensamento, a qual, por n\u00e3o ser ilimitada, sujeita-lhes \u00e0 possibilidade de serem condenados pelos abusos que venham a praticar em rela\u00e7\u00e3o aos direitos de terceiros, abrangidos ou n\u00e3o pela rede social&#8221; (REsp 1650725\/MG, Rel. Ministra NANCY ANDRIGHI, TERCEIRA TURMA, julgado em 18\/05\/2017, DJe 26\/05\/2017).<\/p>\n\n\n\n<h3>Conclus\u00e3o<\/h3>\n\n\n\n<p>\u00c9 assegurado \u00e0 crian\u00e7a e adolescente participar da vida familiar da fam\u00edlia natural (pais e filhos) e da fam\u00edlia extensa, formada por parentes pr\u00f3ximos com os quais a crian\u00e7a ou adolescente convive e mant\u00e9m v\u00ednculos de afinidade e afetividade.<\/p>\n\n\n\n<p>A madrasta \u00e9 parente por afinidade do enteado e por tanto faz parte da fam\u00edlia extensa da crian\u00e7a ou do adolescente.<\/p>\n\n\n\n<p>E apesar de o direito de imagem ser garantido, inclusive constitucionalmente, n\u00e3o h\u00e1 qualquer impedimento de se divulgar foto em momento de divers\u00e3o, relacionamento em fam\u00edlia, como homenagem ou demonstra\u00e7\u00e3o de afeto.<\/p>\n\n\n\n<p>\u00c9 proibido divulgar foto\/v\u00eddeo que tenha o cond\u00e3o de ofender a honra e a imagem, expor a situa\u00e7\u00e3o vexat\u00f3ria, humilhante, constrangedora que ridicularize a crian\u00e7a ou adolescente!<\/p>\n\n\n\n<p>Sendo assim, n\u00e3o h\u00e1 impedimento para a madrasta ou padrasto divulgar foto\/v\u00eddeo do enteado, assim como qualquer outro membro da fam\u00edlia extensa, desde que seja autorizado por um dos respons\u00e1veis pelo menor (pai ou m\u00e3e); observando tamb\u00e9m a vontade da crian\u00e7a ou adolescente na hora de fazer o registro do momento em foto ou v\u00eddeo e tamb\u00e9m permitir que seja divulgado, desde que a foto\/v\u00eddeo n\u00e3o tenha o cond\u00e3o de ofender a honra e a imagem, expor \u00e0 risco e a situa\u00e7\u00e3o vexat\u00f3ria, humilhante, constrangedora que ridicularize a crian\u00e7a ou o adolescente!<\/p>\n\n\n\n<p>Por Bre<strong>nda Viana<\/strong><\/p>\n\n\n\n<p><strong>OAB\/DF 29.206<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"755\" height=\"406\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/10\/images.jpeg\" alt=\"\" class=\"wp-image-2909\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/10\/images.jpeg 755w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/10\/images-300x161.jpeg 300w\" sizes=\"(max-width: 755px) 100vw, 755px\" \/><figcaption>Foto: Ilustrativa<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Para que voc\u00ea entenda como lidar com essa situa\u00e7\u00e3o \u00e9 importante voc\u00ea entender 6 (seis) coisas:<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2019\/10\/07\/madrasta-padrasto-pode-postar-foto-com-meu-filho-nas-redes-sociais\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":2910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2908"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2908"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2908\/revisions"}],"predecessor-version":[{"id":2911,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2908\/revisions\/2911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/2910"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}