{"id":2897,"date":"2019-10-08T07:47:29","date_gmt":"2019-10-08T10:47:29","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=2897"},"modified":"2019-10-07T22:26:41","modified_gmt":"2019-10-08T01:26:41","slug":"justica-prorroga-permanencia-no-presidio-federal-mossoro-de-pm-acusado-de-liderar-quadrilha","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2019\/10\/08\/justica-prorroga-permanencia-no-presidio-federal-mossoro-de-pm-acusado-de-liderar-quadrilha\/","title":{"rendered":"Justi\u00e7a prorroga perman\u00eancia,  no pres\u00eddio federal Mossor\u00f3, de PM acusado de liderar quadrilha"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"635\" height=\"480\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/10\/640x480-3dbb7d8324c858f5a7501f85b1f3d830.jpg\" alt=\"\" class=\"wp-image-2898\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/10\/640x480-3dbb7d8324c858f5a7501f85b1f3d830.jpg 635w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/10\/640x480-3dbb7d8324c858f5a7501f85b1f3d830-300x227.jpg 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/><figcaption>(Foto: Reprodu\u00e7\u00e3o\/Facebook)<\/figcaption><\/figure>\n\n\n\n<p>A Justi\u00e7a Federal prorrogou por mais 360 dias a perman\u00eancia dos presos Silvio C\u00e9sar Molina (policial militar apontado como chefe de quadrilha), Douglas Alves Rocha e Jefferson Alves Rocha, alvos da opera\u00e7\u00e3o La\u00e7os de Fam\u00edlia, na penitenci\u00e1ria federal de Mossor\u00f3 (Rio Grande do Norte). A decis\u00e3o veio perto do fim do prazo, que terminaria na pr\u00f3xima quinta-feira (dia 10).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>No ano passado, a transfer\u00eancia foi realizada sob os argumentos de risco de fuga, participa\u00e7\u00e3o em organiza\u00e7\u00e3o criminosa de \u00e2mbito nacional e com intera\u00e7\u00f5es internacionais, alta periculosidade e privil\u00e9gios junto \u00e0s institui\u00e7\u00f5es p\u00fablicas.<\/p>\n\n\n\n<p>O MPF (Minist\u00e9rio P\u00fablico Federal) solicitou a renova\u00e7\u00e3o do prazo de perman\u00eancia dos r\u00e9us no pres\u00eddio federal de Mossor\u00f3, com justificativa de que os fundamentos que legitimaram a inclus\u00e3o definitiva na unidade penal seguem inalterados.<\/p>\n\n\n\n<p>A defesa afirma que n\u00e3o h\u00e1 qualquer elemento que comprove a suposta tentativa de fuga dos r\u00e9us, que a perman\u00eancia dos custodiados em Mossor\u00f3 gera enorme preju\u00edzo aos acusados e que a transfer\u00eancia para Mato Grosso do Sul facilitaria, inclusive, os interrogat\u00f3rios.<\/p><div class=\"obnsb6a04f8580bfe3\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.obnsb6a04f8580bfe3 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.obnsb6a04f8580bfe3 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.obnsb6a04f8580bfe3 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.obnsb6a04f8580bfe3 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.obnsb6a04f8580bfe3 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.obnsb6a04f8580bfe3 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"caimt6a04f8580bfc7\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.caimt6a04f8580bfc7 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.caimt6a04f8580bfc7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.caimt6a04f8580bfc7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.caimt6a04f8580bfc7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.caimt6a04f8580bfc7 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.caimt6a04f8580bfc7 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Conforme decis\u00e3o da 3\u00aa Vara da Justi\u00e7a Federal de Campo Grande, que prorrogou a perman\u00eancia em Mossor\u00f3, a \u201cinflu\u00eancia e articula\u00e7\u00e3o do grupo permite concluir que a custodia dos r\u00e9us em estabelecimento inadequado permitiria, inclusive, o dom\u00ednio do tr\u00e1fico de drogas na regi\u00e3o, mesmo de dentro da pris\u00e3o\u201d.<\/p>\n\n\n\n<p><strong>PCC<\/strong>&nbsp;&#8211; De acordo com as investiga\u00e7\u00f5es da Pol\u00edcia Federal, que deflagrou a opera\u00e7\u00e3o em junho de 2018, o policial militar Silvio C\u00e9sar Molina Azevedo liderava um grupo que atuava com caracter\u00edsticas de m\u00e1fia em Mundo Novo, a 476 km de Campo Grande, e tinha rela\u00e7\u00f5es comerciais no tr\u00e1fico de maconha com a fac\u00e7\u00e3o criminosa PCC (Primeiro Comando da Capital).<\/p>\n\n\n\n<p>O principal processo da La\u00e7os de Fam\u00edlia tem 19 r\u00e9us e uma s\u00e9ries de crimes: tr\u00e1fico de drogas, associa\u00e7\u00e3o para o tr\u00e1fico, posse de arma de fogo, evas\u00e3o de divisas e lavagem de dinheiro.<\/p>\n\n\n\n<p><strong>Campo Grande News<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A decis\u00e3o veio perto do fim do prazo, que terminaria na pr\u00f3xima quinta-feira (dia 10).<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2019\/10\/08\/justica-prorroga-permanencia-no-presidio-federal-mossoro-de-pm-acusado-de-liderar-quadrilha\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":2898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2897"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2897"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2897\/revisions"}],"predecessor-version":[{"id":2899,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2897\/revisions\/2899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/2898"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}