{"id":23980,"date":"2022-01-15T12:19:42","date_gmt":"2022-01-15T15:19:42","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=23980"},"modified":"2022-01-15T12:20:24","modified_gmt":"2022-01-15T15:20:24","slug":"grupo-de-advogados-prerrogativas-quer-sergio-moro-preso","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2022\/01\/15\/grupo-de-advogados-prerrogativas-quer-sergio-moro-preso\/","title":{"rendered":"Grupo de advogados Prerrogativas quer Moro preso"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"960\" height=\"540\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/08\/S\u00e9rgio-Moro.jpg\" alt=\"\" class=\"wp-image-227\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/08\/S\u00e9rgio-Moro.jpg 960w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/08\/S\u00e9rgio-Moro-300x169.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/08\/S\u00e9rgio-Moro-768x432.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption>Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>Integrante do Prerrogativas, grupo de advogados que tem marcado posi\u00e7\u00e3o contra a&nbsp;<strong>Lava-Jato<\/strong>&nbsp;e que comp\u00f5e as bancas de defesa de investigados no petrol\u00e3o, o criminalista&nbsp;<strong>Antonio Carlos de Almeida Castro, o Kakay<\/strong>, atacou nesta sexta-feira 14 o&nbsp;<strong>ex-juiz Sergio Moro<\/strong>, que em&nbsp;<a href=\"https:\/\/veja.abril.com.br\/politica\/sergio-moro-eleger-lula-ou-bolsonaro-e-suicidio\/\"><strong>entrevista a VEJA<\/strong><\/a>&nbsp;disse que grande parte das cr\u00edticas contra as investiga\u00e7\u00f5es vieram de defensores que \u201ctrabalham pela impunidade de corruptos\u201d. Para Kakay, o ex-magistrado utilizou a opera\u00e7\u00e3o em benef\u00edcio pr\u00f3prio, tolheu o direito de defesa de investigados e deve responder judicialmente por abusos cometidos contra os r\u00e9us. Ao final de todos os recursos judiciais que eventualmente apresente, continua o advogado, Sergio Moro deve ser preso.<\/p>\n\n\n\n<p>A manifesta\u00e7\u00e3o do advogado \u00e9 uma provoca\u00e7\u00e3o a uma das principais bandeiras de Moro, a&nbsp;<strong>execu\u00e7\u00e3o da pena ap\u00f3s a segunda inst\u00e2ncia<\/strong>, tese que permitiu que condenados como o ex-presidente Lula e pr\u00f3ceres do partido, como Jos\u00e9 Dirceu e Jo\u00e3o Vaccari Neto, acabassem, ainda que temporariamente, atr\u00e1s das grades na Lava-Jato.<\/p>\n\n\n\n<p>\u201cA vis\u00e3o que este ex-juiz tem da advocacia \u2013 ao dizer que defendemos a impunidade e a corrup\u00e7\u00e3o \u2013 \u00e9 de algu\u00e9m que instrumentalizou o Judici\u00e1rio por um projeto pessoal. Defendemos as garantias constitucionais, como a presun\u00e7\u00e3o de inoc\u00eancia, para todos, inclusive para ele e o bando que ele coordena. Queremos que ele responda pelos crimes que cometeu usufruindo de todos os direitos que ele negava enquanto juiz. Inclusive o da pris\u00e3o s\u00f3 ap\u00f3s o tr\u00e2nsito em julgado\u201d, disse Kakay a VEJA.<\/p><div class=\"xrcvy6a04c1ab54e60\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.xrcvy6a04c1ab54e60 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.xrcvy6a04c1ab54e60 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.xrcvy6a04c1ab54e60 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.xrcvy6a04c1ab54e60 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.xrcvy6a04c1ab54e60 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.xrcvy6a04c1ab54e60 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"nwqoi6a04c1ab54e33\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.nwqoi6a04c1ab54e33 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.nwqoi6a04c1ab54e33 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.nwqoi6a04c1ab54e33 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.nwqoi6a04c1ab54e33 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.nwqoi6a04c1ab54e33 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.nwqoi6a04c1ab54e33 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Ao longo da Lava-Jato, o Prerrogativas promoveu diversos debates ao vivo com ministros do Supremo Tribunal Federal (STF) e com o procurador-geral da Rep\u00fablica Augusto Aras, dois focos das cr\u00edticas que Moro, hoje pr\u00e9-candidato \u00e0 Presid\u00eancia da Rep\u00fablica pelo Podemos, fez em entrevista a VEJA. Recentemente os mesmos advogados promoveram um jantar com o ex-presidente Lula e o ex-tucano Geraldo Alckmin, que ensaiam a composi\u00e7\u00e3o de um chapa para a disputa ao Pal\u00e1cio do Planalto.<\/p>\n\n\n\n<p>\u201cEnfrentamos desde o in\u00edcio a prepot\u00eancia e o abuso representados pelo Moro, que corrompeu o sistema de justi\u00e7a. Ser atacado por ele indica que estamos do lado certo\u201d, completou o advogado. Na mais reveladora entrevista que concedeu desde que se lan\u00e7ou postulante ao Pal\u00e1cio do Planalto, Sergio Moro afirmou que \u201cgrande parte as cr\u00edticas [\u00e0 Lava-Jato] v\u00eam de advogados que t\u00eam interesse na anula\u00e7\u00e3o das condena\u00e7\u00f5es de seus clientes. Houve um gigantesco esquema de corrup\u00e7\u00e3o, que perdurou por dez anos, e h\u00e1 um grupo de advogados, como esse Prerrogativas, trabalhando pela impunidade daqueles corruptos e vem se arvorar de alguma esp\u00e9cie de \u00e9tica, alguma esp\u00e9cie de superioridade moral em rela\u00e7\u00e3o ao Minist\u00e9rio P\u00fablico e em rela\u00e7\u00e3o aos ju\u00edzes que participaram desses casos? No fundo a vergonha est\u00e1 neles\u201d.<\/p>\n\n\n\n<p>Veja<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Integrante do Prerrogativas, grupo de advogados que tem marcado posi\u00e7\u00e3o contra a&nbsp;Lava-Jato&nbsp;e que comp\u00f5e as bancas de defesa de investigados no petrol\u00e3o, o criminalista&nbsp;Antonio Carlos de Almeida Castro, o Kakay, atacou nesta sexta-feira 14 o&nbsp;ex-juiz Sergio Moro, que em&nbsp;entrevista a VEJA&nbsp;disse que grande parte das cr\u00edticas contra as investiga\u00e7\u00f5es vieram de defensores que \u201ctrabalham pela<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2022\/01\/15\/grupo-de-advogados-prerrogativas-quer-sergio-moro-preso\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23980"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23980"}],"version-history":[{"count":3,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23980\/revisions"}],"predecessor-version":[{"id":23983,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23980\/revisions\/23983"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}