{"id":2385,"date":"2019-09-19T17:20:23","date_gmt":"2019-09-19T20:20:23","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=2385"},"modified":"2019-09-20T15:42:08","modified_gmt":"2019-09-20T18:42:08","slug":"oab-rn-e-marcco-lancarao-1o-projeto-de-iniciativa-popular-digital-para-que-apenas-fichas-limpas-ocupem-cargos-comissionados-no-rn","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/19\/oab-rn-e-marcco-lancarao-1o-projeto-de-iniciativa-popular-digital-para-que-apenas-fichas-limpas-ocupem-cargos-comissionados-no-rn\/","title":{"rendered":"OAB-RN e MARCCO lan\u00e7ar\u00e3o 1\u00ba   projeto de iniciativa popular digital para que apenas fichas limpas ocupem cargos comissionados no RN"},"content":{"rendered":"\n<p>A Ordem dos Advogados do Brasil no Rio Grande do Norte (OAB-RN) e o Movimento Articulado de Combate a Corrup\u00e7\u00e3o (Marcoo) v\u00e3o apresentar na pr\u00f3xima segunda-feira (23) o primeiro projeto de iniciativa popular com assinatura digital do pa\u00eds. Atrav\u00e9s de ades\u00e3o via aplicativo de celular, a OAB\/RN incentivar\u00e1 as pessoas a serem coautoras do projeto de lei que exige ficha limpa e crit\u00e9rios t\u00e9cnicos para cargos comissionados no \u00e2mbito do Governo do Rio Grande do Norte. O evento acontecer\u00e1 \u00e0s 11 horas, no plen\u00e1rio da Seccional Potiguar, e contar\u00e1 com a presen\u00e7a do jurista Marlon Reis (ex-magistrado brasileiro e relator da Lei da Ficha Limpa nacional).<\/p>\n\n\n\n<p>Ap\u00f3s conseguir o n\u00famero de assinaturas digitais suficientes, a OAB vai dar entrada com o projeto de lei direto no protocolo da Assembleia Legislativa do Estado, sem que tenha que submet\u00ea-lo ao interm\u00e9dio de um parlamentar. Um fato in\u00e9dito no processo pol\u00edtico nacional, j\u00e1 que o Rio Grande do Norte \u00e9 o \u00fanico a ter uma legisla\u00e7\u00e3o que permite a apresenta\u00e7\u00e3o de projetos de iniciativa popular endossados por assinaturas digitais. Antes, s\u00f3 os deputados podiam dar entrada em propostas legislativas.<\/p>\n\n\n\n<p>A legisla\u00e7\u00e3o voltada para essa finalidade vem sendo aprovada e aperfei\u00e7oada desde 2014 pela Assembleia Legislativa do Estado, por meio da Emenda Constitucional n\u00b0 013\/2014, da Lei n\u00b0 10.140\/2016 e da Lei n\u00b0 10.513\/2019. Todas de autoria do deputado estadual Kelps Lima. Antes dessas tr\u00eas leis, somente os deputados, o Executivo e o Judici\u00e1rio podiam propor leis ao Parlamento estadual.<\/p>\n\n\n\n<p>A lei mais recente, n\u00b0 10.513\/2019, abriu caminho para que a coleta dessas assinaturas seja via digital, pelo celular. At\u00e9 ent\u00e3o, a prospec\u00e7\u00e3o de ades\u00f5es tinha que ser mec\u00e2nica, com milhares de pessoas preenchendo folhas de papel. A iniciativa popular, conforme estabelece a lei 10.140\/2016, \u00e9 formada por, no m\u00ednimo, tr\u00eas por cento do eleitorado que tenha votado nas \u00faltimas elei\u00e7\u00f5es gerais do Estado, distribu\u00eddo, no m\u00ednimo, em tr\u00eas quintos dos munic\u00edpios, com n\u00e3o menos de um por cento de eleitores de cada um deles.<\/p><div class=\"ffqkr6a97be443a0b8\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ffqkr6a97be443a0b8 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ffqkr6a97be443a0b8 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ffqkr6a97be443a0b8 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ffqkr6a97be443a0b8 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ffqkr6a97be443a0b8 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ffqkr6a97be443a0b8 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"wabjk6a97be443a0a3\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.wabjk6a97be443a0a3 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.wabjk6a97be443a0a3 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.wabjk6a97be443a0a3 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.wabjk6a97be443a0a3 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.wabjk6a97be443a0a3 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.wabjk6a97be443a0a3 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O aplicativo a ser usado para a coleta de assinaturas ser\u00e1 o \u201cMudamos\u201d, criado pelo Instituto de Tecnologia e Sociedade do Rio (ITS Rio) e destinado exatamente ao acolhimento de ades\u00f5es digitais. As assinaturas reunidas pelo app j\u00e1 s\u00e3o certificadas pelo ITS Rio, que tem um protocolo t\u00e9cnico firmado com a Assembleia Legislativa para que sejam reconhecidas pela Casa as ades\u00f5es feitas pela plataforma.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"700\" height=\"700\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/IMG-20190919-WA0064.jpg\" alt=\"\" class=\"wp-image-2386\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/IMG-20190919-WA0064.jpg 700w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/IMG-20190919-WA0064-150x150.jpg 150w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/IMG-20190919-WA0064-300x300.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s conseguir o n\u00famero de assinaturas digitais suficientes, a OAB vai dar entrada com o projeto de lei direto no protocolo da Assembleia Legislativa<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/19\/oab-rn-e-marcco-lancarao-1o-projeto-de-iniciativa-popular-digital-para-que-apenas-fichas-limpas-ocupem-cargos-comissionados-no-rn\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":2387,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2385"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2385"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2385\/revisions"}],"predecessor-version":[{"id":2388,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2385\/revisions\/2388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/2387"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}