{"id":2380,"date":"2019-09-19T13:31:35","date_gmt":"2019-09-19T16:31:35","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=2380"},"modified":"2019-09-19T13:31:35","modified_gmt":"2019-09-19T16:31:35","slug":"tse-arquiva-acao-de-bolsonaro-contra-folha-de-s-paulo-e-haddad","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/19\/tse-arquiva-acao-de-bolsonaro-contra-folha-de-s-paulo-e-haddad\/","title":{"rendered":"TSE arquiva a\u00e7\u00e3o de Bolsonaro contra Folha de S. Paulo e Haddad"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"543\" height=\"263\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/image001-1.jpg\" alt=\"\" class=\"wp-image-2381\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/image001-1.jpg 543w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/image001-1-300x145.jpg 300w\" sizes=\"(max-width: 543px) 100vw, 543px\" \/><figcaption>Foto: Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>Por unanimidade, o Plen\u00e1rio do Tribunal Superior Eleitoral (TSE) rejeitou uma a\u00e7\u00e3o do presidente da Rep\u00fablica, Jair Bolsonaro, que pedia investiga\u00e7\u00e3o contra Fernando Haddad, seu advers\u00e1rio pol\u00edtico durante a campanha das Elei\u00e7\u00f5es 2018, e o jornal Folha de S. Paulo.<\/p>\n\n\n\n<p>O argumento de Bolsonaro, ainda candidato quando protocolou a a\u00e7\u00e3o, era que Haddad e sua vice, Manuela d\u2019\u00c1vila, teriam se aliado ao jornal para atacar sua campanha, principalmente com a reportagem que denunciou o impulsionamento de mensagens em massa pelo WhatsApp.<\/p>\n\n\n\n<p>O relator da a\u00e7\u00e3o, ministro Jorge Mussi, votou pela improced\u00eancia dos argumentos e determinou o arquivamento do processo.<\/p>\n\n\n\n<p>Durante seu voto, Mussi destacou o princ\u00edpio constitucional da liberdade de express\u00e3o e afirmou que a atua\u00e7\u00e3o da Justi\u00e7a Eleitoral em situa\u00e7\u00f5es que envolvem os meios de comunica\u00e7\u00e3o social deve ser realizada com a menor interfer\u00eancia poss\u00edvel, de modo a prevalecer a livre manifesta\u00e7\u00e3o do pensamento e o direito de informa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Ele afirmou que a Constitui\u00e7\u00e3o Federal \u00e9 cristalina ao estabelecer, em seu artigo 220, que \u201ca manifesta\u00e7\u00e3o do pensamento, a cria\u00e7\u00e3o, a express\u00e3o e a informa\u00e7\u00e3o sob qualquer forma, processo ou ve\u00edculo n\u00e3o sofrer\u00e3o qualquer restri\u00e7\u00e3o\u201d. Segundo o relator, esse princ\u00edpio garante o pluralismo de opini\u00f5es, instrumento essencial para a consolida\u00e7\u00e3o do estado democr\u00e1tico de Direito.<\/p><div class=\"gaugr6a97fdf6daa5f\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.gaugr6a97fdf6daa5f {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.gaugr6a97fdf6daa5f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.gaugr6a97fdf6daa5f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.gaugr6a97fdf6daa5f {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.gaugr6a97fdf6daa5f {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.gaugr6a97fdf6daa5f {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"kcitc6a97fdf6daa49\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.kcitc6a97fdf6daa49 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.kcitc6a97fdf6daa49 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.kcitc6a97fdf6daa49 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.kcitc6a97fdf6daa49 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.kcitc6a97fdf6daa49 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.kcitc6a97fdf6daa49 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Para Mussi, no caso dos autos, as mat\u00e9rias jornal\u00edsticas est\u00e3o fundadas em rela\u00e7\u00e3o indissoci\u00e1vel entre a liberdade de imprensa, de express\u00e3o e democracia.<\/p>\n\n\n\n<p>De acordo com o magistrado, n\u00e3o se sustenta o argumento de que houve conluio entre os advers\u00e1rios de Bolsonaro e o jornal. Tampouco, disse ele, houve prova de que o material divulgado pela publica\u00e7\u00e3o seria not\u00edcia inver\u00eddica, infundada, depreciativa, difamat\u00f3ria, ou criminosa.<\/p>\n\n\n\n<p>Mussi destacou que a rep\u00f3rter autora da reportagem colheu a manifesta\u00e7\u00e3o de todos os envolvidos, assegurando-lhes, de forma inequ\u00edvoca, a apresenta\u00e7\u00e3o de duas vers\u00f5es acerca dos fatos e que, al\u00e9m disso, a reportagem informou na ocasi\u00e3o que n\u00e3o havia a indica\u00e7\u00e3o de que Bolsonaro, ou sua equipe de campanha, soubesse que o servi\u00e7o estava sendo contratado.<\/p>\n\n\n\n<p>\u201cEssa circunst\u00e2ncia, a meu sentir, afasta peremptoriamente a alega\u00e7\u00e3o de estratagema previamente discutida entre os investigados e por eles organizada para promover campanha contra Jair Bolsonaro\u201d, finalizou o ministro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O relator da a\u00e7\u00e3o, ministro Jorge Mussi, votou pela improced\u00eancia dos argumentos e determinou o arquivamento do processo.<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/19\/tse-arquiva-acao-de-bolsonaro-contra-folha-de-s-paulo-e-haddad\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":2381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2380"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2380"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2380\/revisions"}],"predecessor-version":[{"id":2382,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2380\/revisions\/2382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/2381"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}