{"id":2361,"date":"2019-09-19T15:18:24","date_gmt":"2019-09-19T18:18:24","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=2361"},"modified":"2019-09-19T10:04:24","modified_gmt":"2019-09-19T13:04:24","slug":"oleo-nas-praias-do-rn-mpf-articula-orgaos-pela-limpeza-e-investigacao-da-origem-dos-residuos","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/19\/oleo-nas-praias-do-rn-mpf-articula-orgaos-pela-limpeza-e-investigacao-da-origem-dos-residuos\/","title":{"rendered":"\u00d3leo nas praias do RN: MPF articula \u00f3rg\u00e3os pela limpeza e investiga\u00e7\u00e3o da origem dos res\u00edduos"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1000\" height=\"493\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/d7557039184c468ecbeb3c167c65ea66e1834b7b9c21521acd7efb7643ad5291-1000x493.jpg\" alt=\"\" class=\"wp-image-2362\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/d7557039184c468ecbeb3c167c65ea66e1834b7b9c21521acd7efb7643ad5291-1000x493.jpg 1000w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/d7557039184c468ecbeb3c167c65ea66e1834b7b9c21521acd7efb7643ad5291-1000x493-300x148.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/d7557039184c468ecbeb3c167c65ea66e1834b7b9c21521acd7efb7643ad5291-1000x493-768x379.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption>Foto: Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>Em audi\u00eancia na sede do Minist\u00e9rio P\u00fablico Federal no Rio Grande do Norte (MPF\/RN), nessa ter\u00e7a-feira (17), o procurador da Rep\u00fablica Victor Mariz reuniu representantes do MP Estadual, Ibama, Idema, Defesa Civil, Capitania dos Portos, Pol\u00edcia Federal e dos munic\u00edpios de Parnamirim, N\u00edsia Floresta e Goianinha para discutir o aparecimento de manchas de \u00f3leo em praias do litoral potiguar. O objetivo \u00e9 somar esfor\u00e7os para limpeza e descarte adequado dos res\u00edduos, al\u00e9m de identificar a origem e respons\u00e1veis pelo derramamento.<\/p>\n\n\n\n<p>A servidora do Ibama, Fab\u00edola Patr\u00edcia, apresentou as informa\u00e7\u00f5es colhidas, at\u00e9 ent\u00e3o, sobre o tipo do res\u00edduo, poss\u00edveis causas do seu aparecimento e locais identificados. Uma amostra do material foi enviada para an\u00e1lise em laborat\u00f3rio no Rio de Janeiro. O instituto deve concluir mapeamento das \u00e1reas afetadas no RN, por meio da realiza\u00e7\u00e3o de sobrevoos e vistoria por terra, at\u00e9 esta sexta-feira (20). Ela ressaltou a necessidade da retirada do \u00f3leo das praias, cost\u00f5es rochosos e vegeta\u00e7\u00f5es atingidos, para evitar a contamina\u00e7\u00e3o de outras \u00e1reas pela a\u00e7\u00e3o di\u00e1ria das mar\u00e9s.<\/p>\n\n\n\n<p>Para Victor Mariz, \u201cficou clara a import\u00e2ncia da limpeza urgente das \u00e1reas afetadas. Para isso, \u00e9 imperioso o engajamento de todos, a come\u00e7ar pelos \u00f3rg\u00e3os presentes na reuni\u00e3o.\u201d O MPF requisitou ao Ibama e Idema orienta\u00e7\u00f5es t\u00e9cnicas sobre a subst\u00e2ncia e a forma adequada de coleta, armazenamento e descarte. Esse material ser\u00e1 reunido em recomenda\u00e7\u00e3o, a ser enviada para as prefeituras dos munic\u00edpios afetados, a fim de minimizar riscos para banhistas e trabalhadores.<\/p><div class=\"vtwsv6a97e6d6d8286\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.vtwsv6a97e6d6d8286 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.vtwsv6a97e6d6d8286 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vtwsv6a97e6d6d8286 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vtwsv6a97e6d6d8286 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vtwsv6a97e6d6d8286 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vtwsv6a97e6d6d8286 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"tzemb6a97e6d6d8269\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.tzemb6a97e6d6d8269 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.tzemb6a97e6d6d8269 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.tzemb6a97e6d6d8269 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.tzemb6a97e6d6d8269 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.tzemb6a97e6d6d8269 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.tzemb6a97e6d6d8269 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p><strong>Laudo&nbsp;<\/strong>&#8211; A an\u00e1lise do \u00f3leo tamb\u00e9m ir\u00e1 subsidiar a investiga\u00e7\u00e3o da origem da subst\u00e2ncia. Em relato preliminar, a Petrobras informou ao Ibama que n\u00e3o se trata de \u00f3leo utilizado pela empresa. Ainda \u00e9 aguardado laudo final, pedido pelo Ibama e MPF, que deve conter mais informa\u00e7\u00f5es sobre a composi\u00e7\u00e3o das manchas.<\/p>\n\n\n\n<p>O MPF solicitou, ainda, ao Idema, a realiza\u00e7\u00e3o de campanha ambiental educativa para conscientiza\u00e7\u00e3o de banhistas sobre os poss\u00edveis efeitos do contato com o \u00f3leo e os cuidados necess\u00e1rios. Tamb\u00e9m foi solicitado apoio ao Departamento de Oceanografia e Limnologia da UFRN, por meio de estudos informa\u00e7\u00f5es pertinentes.<\/p>\n\n\n\n<p><strong>\u00d3leo&nbsp;<\/strong>-As primeiras manchas de \u00f3leo apareceram no litoral do Nordeste no come\u00e7o de setembro. No RN, foram identificadas h\u00e1 cerca de 10 dias, em diferentes pontos do litoral, trazidas pela mar\u00e9. At\u00e9 o momento, a \u00e1rea com maior concentra\u00e7\u00e3o de res\u00edduos \u00e9 Barra de Tabatinga, em N\u00edsia Floresta, litoral Sul do estado, principalmente nos rochedos. O Ibama tamb\u00e9m identificou as manchas na Via costeira, praia de Piramb\u00fazios, Perobas, Jacum\u00e3, B\u00fazios, Camurupim, Pirangi do Sul e Maxaranguape. A mesma subst\u00e2ncia tamb\u00e9m foi encontrada em praias de Sergipe, Alagoas, Pernambuco, Para\u00edba e, nos \u00faltimos dias, no Piau\u00ed e Maranh\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recomenda\u00e7\u00e3o com orienta\u00e7\u00f5es sobre coleta, armazenamento e descarte do produto ser\u00e1 enviada \u00e0s prefeituras dos munic\u00edpios atingidos<\/p>\n<p><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/19\/oleo-nas-praias-do-rn-mpf-articula-orgaos-pela-limpeza-e-investigacao-da-origem-dos-residuos\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":2362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2361"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2361"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2361\/revisions"}],"predecessor-version":[{"id":2363,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2361\/revisions\/2363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/2362"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}