{"id":2342,"date":"2019-09-19T07:30:50","date_gmt":"2019-09-19T10:30:50","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=2342"},"modified":"2019-09-19T07:30:50","modified_gmt":"2019-09-19T10:30:50","slug":"educadora-feita-refem-durante-rebeliao-no-ceduc-de-caico-sera-indenizada-pelo-estado","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/19\/educadora-feita-refem-durante-rebeliao-no-ceduc-de-caico-sera-indenizada-pelo-estado\/","title":{"rendered":"Educadora feita ref\u00e9m durante rebeli\u00e3o no Ceduc de Caic\u00f3 ser\u00e1 indenizada pelo Estado"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"550\" height=\"293\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/ceduccaico.jpg\" alt=\"\" class=\"wp-image-2343\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/ceduccaico.jpg 550w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/ceduccaico-300x160.jpg 300w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><figcaption>Foto: DIvulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>O juiz Luiz Ant\u00f4nio Tomaz do Nascimento, da 2\u00aa Vara C\u00edvel da comarca de Caic\u00f3, condenou o Estado do Rio Grande do Norte a indenizar em R$ 5 mil, a t\u00edtulo de danos morais, uma educadora social que foi feita ref\u00e9m durante uma rebeli\u00e3o no Ceduc de Caic\u00f3, ocorrida em mar\u00e7o de 2015. Sobre o valor dever\u00e1 incidir juros desde o evento danoso e atualiza\u00e7\u00e3o monet\u00e1ria a partir da senten\u00e7a.<\/p>\n\n\n\n<p>A autora afirmou ser Educadora Social e que em 17 de mar\u00e7o de 2015, durante o exerc\u00edcio de suas fun\u00e7\u00f5es no Centro Educacional de Caic\u00f3 foi feita ref\u00e9m, com outros educadores e a partir desse momento iniciou-se uma rebeli\u00e3o. Narrou que um adolescente colocou uma chave de fenda no seu pesco\u00e7o e imobilizou-a, e que durante o movimento sofreu amea\u00e7a de morte, al\u00e9m de agress\u00f5es de ordens f\u00edsicas, psicol\u00f3gicas e morais.<\/p>\n\n\n\n<p>Alegou que em raz\u00e3o do abalo psicol\u00f3gico decorrente dessa situa\u00e7\u00e3o, necessitou de acompanhamento psiqui\u00e1trico e se afastou de suas atividades. Atribuiu ao Estado a responsabilidade pela omiss\u00e3o ao dever legal de seguran\u00e7a. Requereu indeniza\u00e7\u00e3o por dano moral no valor sugerido de R$ 200 mil.<\/p>\n\n\n\n<p><strong>Decis\u00e3o<\/strong><\/p>\n\n\n\n<p>Ao decidir sobre o caso, o magistrado Luiz Ant\u00f4nio do Nascimento aponta que a autora foi submetida a atendimento psicol\u00f3gico, necessitando de um per\u00edodo de afastamento de suas atividades profissionais normais a fim de recuperar-se do choque sofrido, permaneceu 90 dias de atestado m\u00e9dico e, por fim, passou 180 dias em readapta\u00e7\u00e3o de fun\u00e7\u00e3o e que \u00e9 indiscut\u00edvel que do ocorrido resultaram danos psicol\u00f3gicos a demandante e que as provas dos autos n\u00e3o deixam d\u00favida de que houve falha na fiscaliza\u00e7\u00e3o dos menores infratores, o que viabilizou a rebeli\u00e3o e que a exist\u00eancia de armas brancas permitiu que os rebelados rendessem os agentes educadores, entre eles a autora, garantindo o \u00eaxito do motim.<\/p><div class=\"dwcpg6a04b4ab388cb\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.dwcpg6a04b4ab388cb {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.dwcpg6a04b4ab388cb {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.dwcpg6a04b4ab388cb {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.dwcpg6a04b4ab388cb {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.dwcpg6a04b4ab388cb {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.dwcpg6a04b4ab388cb {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"pnxzk6a04b4ab388b0\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.pnxzk6a04b4ab388b0 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.pnxzk6a04b4ab388b0 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.pnxzk6a04b4ab388b0 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.pnxzk6a04b4ab388b0 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.pnxzk6a04b4ab388b0 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.pnxzk6a04b4ab388b0 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O magistrado destacou que de acordo com o relato da autora e testemunhas em audi\u00eancia, os infratores estavam recebendo ordens de algum meliante que estava preso no pres\u00eddio de Alca\u00e7uz, tudo mediante contato telef\u00f4nico, corroborando para a eclos\u00e3o da rebeli\u00e3o e que a atua\u00e7\u00e3o deficiente da administra\u00e7\u00e3o justifica a condena\u00e7\u00e3o a reparar os danos causados por omiss\u00e3o.<\/p>\n\n\n\n<p>O julgador salienta que a atividade de educador de adolescentes no cumprimento de medidas socioeducativas em entidades de interna\u00e7\u00e3o, mediante contato com adolescentes infratores, exp\u00f5e o funcion\u00e1rio a risco natural e inerente da profiss\u00e3o, tal como afirma o r\u00e9u. \u201cContudo, permanecer ref\u00e9m, sob amea\u00e7a de morte, extrapola os limites da sua fun\u00e7\u00e3o. Certamente ningu\u00e9m est\u00e1 preparado psicologicamente para vivenciar a f\u00faria de internos sofrendo agress\u00f5es e amea\u00e7as, de modo que os reflexos dessa situa\u00e7\u00e3o s\u00e3o inevit\u00e1veis e imensur\u00e1veis\u201d.<\/p>\n\n\n\n<p>Assim, o magistrado Luiz Ant\u00f4nio do Nascimento decidiu que a responsabilidade do r\u00e9u \u00e9 ineg\u00e1vel, diante do nexo causal entre a falha da seguran\u00e7a do centro educacional, que culminou na rebeli\u00e3o, e os danos morais sofridos pela autora, raz\u00e3o pela qual ela deve reparar os danos decorrentes do evento.<\/p>\n\n\n\n<p>No tocante ao montante da indeniza\u00e7\u00e3o, entendeu ser desproporcional e excessivo o pedido inicial no montante de R$ 200 mil e que o valor de R$ 5 mil atende ao requisito de razoabilidade, de modo a compensar a v\u00edtima, sem implicar enriquecimento nem empobrecimento dos envolvidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A autora afirmou ser Educadora Social e que em 17 de mar\u00e7o de 2015, durante o exerc\u00edcio de suas fun\u00e7\u00f5es no Centro Educacional de Caic\u00f3 foi feita ref\u00e9m<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/19\/educadora-feita-refem-durante-rebeliao-no-ceduc-de-caico-sera-indenizada-pelo-estado\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":2343,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2342"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2342"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2342\/revisions"}],"predecessor-version":[{"id":2344,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2342\/revisions\/2344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/2343"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}