{"id":2295,"date":"2019-09-18T09:05:20","date_gmt":"2019-09-18T12:05:20","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=2295"},"modified":"2019-09-18T08:25:02","modified_gmt":"2019-09-18T11:25:02","slug":"advogado-sera-indenizado-em-r-46-mil-por-atraso-em-voo-para-natal","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/18\/advogado-sera-indenizado-em-r-46-mil-por-atraso-em-voo-para-natal\/","title":{"rendered":"Advogado ser\u00e1 indenizado em R$ 4,6 mil por atraso em voo para Natal"},"content":{"rendered":"\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/download-1.jpg\" alt=\"\" class=\"wp-image-2296\" width=\"405\" height=\"228\"\/><figcaption>Foto: Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>A 2\u00aa C\u00e2mara C\u00edvel do Tribunal de Justi\u00e7a, \u00e0 unanimidade, manteve condena\u00e7\u00e3o da empresa Transportes A\u00e9reos Portugueses S\/A a pagar indeniza\u00e7\u00e3o por danos morais e materiais em favor de um advogado causados por atraso de voo internacional. Com isso, a TAP \u2013 Linhas \u00e1reas deve pagar o valor de R$ 4 mil pelos danos morais sofridos e mais o valor de R$ 600 pelos danos materiais experimentados pelo consumidor.<\/p>\n\n\n\n<p>Em 1\u00ba Grau, o advogado afirmou ter realizado contrato de presta\u00e7\u00e3o de servi\u00e7o de transporte a\u00e9reo em voo internacional com a TAP \u2013 Linhas \u00e1reas, bilhete este adquirido pela Smilles e descreveu in\u00fameros problemas ao longo da presta\u00e7\u00e3o do servi\u00e7o, em espec\u00edfico, no voo de regresso Praga \u2013 Natal.<\/p>\n\n\n\n<p>O autor informou que o voo de regresso a Natal, marcado para o dia 23 de setembro de 2017, foi cancelado, fato este que o obrigou a aceitar uma passagem com destino a Recife. No entanto, ao chegar na capital pernambucana, soube que teria de adquirir, por conta pr\u00f3pria, uma outra passagem Recife-Natal. Mencionou que estes fatos lhe geraram, ao todo, um atraso de mais de onze horas em seu retorno.<\/p>\n\n\n\n<p>A 16\u00aa Vara C\u00edvel de Natal condenou a empresa, mas excluiu da a\u00e7\u00e3o a Smilles e condenou o autor ao pagamento dos honor\u00e1rios, em favor dos patronos da empresa, no valor de R$ 500,00. Condenou ainda a TAP \u2013 Linhas A\u00e9reas ao pagamento das custas processuais e honor\u00e1rios de advogado no percentual de 15% em rela\u00e7\u00e3o ao valor da condena\u00e7\u00e3o.<\/p>\n\n\n\n<p>Em recurso de Apela\u00e7\u00e3o, o advogado argumentou sobre a legitimidade da empresa Smiles S\/A para responder a a\u00e7\u00e3o judicial, justificando que as passagens foram adquiridas diretamente junto ao programa de milhas fornecido pela Smiles, a qual se configura como uma parceria firmada entre as empresas a\u00e9reas e a institui\u00e7\u00e3o de milhagem.<\/p>\n\n\n\n<p>Al\u00e9m do mais, enfatizou a necessidade de majora\u00e7\u00e3o da indeniza\u00e7\u00e3o por dano moral, haja vista o atraso total para conclus\u00e3o da viagem em aproximadamente onze horas. Ao final, requereu a reforma da senten\u00e7a para reconhecer a legitimidade da Smiles para figurar como r\u00e9 na a\u00e7\u00e3o e sua condena\u00e7\u00e3o ao pagamento de indeniza\u00e7\u00e3o por danos morais e materiais, al\u00e9m da majora\u00e7\u00e3o do dano moral j\u00e1 arbitrado.<\/p><div class=\"gbbpx6a03ebf712d55\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.gbbpx6a03ebf712d55 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.gbbpx6a03ebf712d55 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.gbbpx6a03ebf712d55 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.gbbpx6a03ebf712d55 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.gbbpx6a03ebf712d55 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.gbbpx6a03ebf712d55 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"ncuby6a03ebf712d37\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ncuby6a03ebf712d37 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ncuby6a03ebf712d37 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ncuby6a03ebf712d37 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ncuby6a03ebf712d37 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ncuby6a03ebf712d37 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ncuby6a03ebf712d37 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p><strong>Voto<\/strong><\/p>\n\n\n\n<p>O relator do recurso, desembargador Ibanez Monteiro, explicou que o C\u00f3digo de Defesa do Consumidor incide nas causas referentes ao transporte a\u00e9reo, haja vista que a rela\u00e7\u00e3o jur\u00eddica mantida pelas partes \u00e9 de natureza consumerista, nos termos do artigo 14.<\/p>\n\n\n\n<p>Esclareceu que, de acordo com a teoria da responsabilidade objetiva, a pessoa que busca ser ressarcida por danos morais sofridos, n\u00e3o precisa demonstrar a culpa do seu causador, sendo suficiente apenas a comprova\u00e7\u00e3o do preju\u00edzo suportado e a rela\u00e7\u00e3o de causalidade entre a atividade il\u00edcita do agente e o dano suportado, com a invers\u00e3o do \u00f4nus probat\u00f3rio que poder\u00e1 recair sobre o prestador de servi\u00e7o.<\/p>\n\n\n\n<p>No caso analisado, considerou incontroverso que houve atraso do voo. Isto porque documento anexado ao processo descreve a aquisi\u00e7\u00e3o de passagem Lisboa \u2013 Natal, com chegada prevista no dia 23 de setembro de 2017, \u00e0s 22h. No entanto, por motivos n\u00e3o esclarecidos, o voo foi cancelado, fato este que obrigou o consumidor a aceitar uma passagem Lisboa \u2013 Recife, com chegada no Brasil na madrugada do dia 24 de setembro de 2017.<\/p>\n\n\n\n<p>Para o relator, n\u00e3o h\u00e1 que falar em legitimidade da empresa Smiles S\/A para responder \u00e0 a\u00e7\u00e3o judicial, haja vista que esta n\u00e3o poderia ter qualquer responsabilidade por atraso do voo da TAP, tratando a hip\u00f3tese de culpa exclusiva da companhia a\u00e9rea. O relator considerou a jurisprud\u00eancia nacional que pacificou o entendimento de que o dano moral decorrente de cancelamento\/atraso de voo evidencia-se pelo desconforto, afli\u00e7\u00e3o e transtornos suportados pelos passageiros, na medida em que derivam do pr\u00f3prio fato.<\/p>\n\n\n\n<p>Por fim, considerou o valor de R$ 4 mil fixado na primeira inst\u00e2ncia para compensar o abalo moral experimentado pelo autor deve ser mantido intacto, n\u00e3o cabendo a majora\u00e7\u00e3o pleiteada, porque foi arbitrado em patamar razo\u00e1vel, considerando o atraso de aproximadamente onze horas e que a viajem foi conclu\u00edda nos dias planejados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com isso, a TAP \u2013 Linhas \u00e1reas deve pagar o valor de R$ 4 mil pelos danos morais sofridos<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/18\/advogado-sera-indenizado-em-r-46-mil-por-atraso-em-voo-para-natal\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":2296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2295"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2295"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2295\/revisions"}],"predecessor-version":[{"id":2297,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2295\/revisions\/2297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/2296"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}