{"id":2255,"date":"2019-09-17T08:16:37","date_gmt":"2019-09-17T11:16:37","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=2255"},"modified":"2019-09-16T23:00:42","modified_gmt":"2019-09-17T02:00:42","slug":"festa-do-boi-empresas-assinam-termos-de-compromisso-com-o-mprn","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/17\/festa-do-boi-empresas-assinam-termos-de-compromisso-com-o-mprn\/","title":{"rendered":"Festa do Boi: Empresas assinam Termos de Compromisso com o MPRN"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"444\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/boi-1024x444.jpg\" alt=\"\" class=\"wp-image-2256\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/boi-1024x444.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/boi-300x130.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/boi-768x333.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2019\/09\/boi.jpg 1138w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: DIvulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p> O Minist\u00e9rio P\u00fablico do Rio Grande do Norte (MPRN) publicou no Di\u00e1rio Oficial do Estado, tr\u00eas Termos de Compromissos de Conduta (TCC) tratando da 57\u00aa edi\u00e7\u00e3o da Festa do Boi, que come\u00e7a em meados de outubro, no Parque de Exposi\u00e7\u00f5es Arist\u00f3fanes Fernandes, em Parnamirim. Um foi firmado com a Associa\u00e7\u00e3o Norte-rio-grandense de Criadores do Estado do Rio Grande do Norte (Anorc), e outros dois com empresas que realizar\u00e3o os shows.\u00a0<\/p>\n\n\n\n<p>Os acordos foram firmados no curso do Inqu\u00e9rito Civil instaurado em julho de 2019, pela 10\u00aa Promotoria de Justi\u00e7a da Comarca de Parnamirim, estabelecendo condi\u00e7\u00f5es para realiza\u00e7\u00e3o de eventos relativos a apresenta\u00e7\u00f5es musicais no Parque de Exposi\u00e7\u00f5es Arist\u00f3fanes Fernandes, por ocasi\u00e3o da Festa do Boi 2019 e tem como finalidade garantir que transcorram com o cumprimento da legisla\u00e7\u00e3o aplic\u00e1vel, garantindo-se os direitos de todos os envolvidos e de terceiros que possam ser atingidos por seus impactos.\u00a0Para David Costa Benevides, titular da 10\u00aa Promotoria de Justi\u00e7a de Parnamirim, a problem\u00e1tica foi tratada com boa anteced\u00eancia. <\/p><div class=\"ceten6a04f010e4abe\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ceten6a04f010e4abe {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ceten6a04f010e4abe {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ceten6a04f010e4abe {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ceten6a04f010e4abe {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ceten6a04f010e4abe {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ceten6a04f010e4abe {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"uvoxe6a04f010e4a9a\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.uvoxe6a04f010e4a9a {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.uvoxe6a04f010e4a9a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.uvoxe6a04f010e4a9a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.uvoxe6a04f010e4a9a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.uvoxe6a04f010e4a9a {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.uvoxe6a04f010e4a9a {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>\u201cN\u00f3s buscamos a cada ano fazer com maior anteced\u00eancia para evitar transtornos pela via judicial. Esse ano, a Anorc se antecipou e providenciou mais cedo parte dos documentos necess\u00e1rios para a realiza\u00e7\u00e3o da festa do boi, como a licen\u00e7a ambiental do parque e a libera\u00e7\u00e3o dos bombeiros, ent\u00e3o por isso que n\u00f3s conseguimos concluir os TCCs mais cedo\u201d, comemora.<\/p>\n\n\n\n<p>\u00a0Os organizadores se comprometeram a cumprir com as obriga\u00e7\u00f5es assumidas para garantir desde benef\u00edcio de meia entrada aos estudantes a quest\u00f5es como polui\u00e7\u00e3o sonora, emiss\u00e3o de poeira, seguran\u00e7a dos animais, limpeza, seguran\u00e7a do evento e regras para presen\u00e7a de crian\u00e7as e adolescentes.\u00a0Para ver os TCCs publicados no Di\u00e1rio Oficial, e todas as condi\u00e7\u00f5es assumidas pelos empres\u00e1rios, clique\u00a0<a href=\"https:\/\/www.mprn.mp.br\/portal\/images\/files\/2019\/20190916_FestadoBoi.pdf\">aqui<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um foi firmado com a Associa\u00e7\u00e3o Norte-rio-grandense de Criadores do Estado do Rio Grande do Norte (Anorc), e outros dois com empresas que realizar\u00e3o os shows<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2019\/09\/17\/festa-do-boi-empresas-assinam-termos-de-compromisso-com-o-mprn\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":2256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2255"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2255"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2255\/revisions"}],"predecessor-version":[{"id":2257,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2255\/revisions\/2257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/2256"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}