{"id":21776,"date":"2021-09-23T11:54:21","date_gmt":"2021-09-23T14:54:21","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=21776"},"modified":"2021-09-23T11:54:21","modified_gmt":"2021-09-23T14:54:21","slug":"trt-rn-movimenta-mais-de-10-milhoes-e-e-destaque-nacional-na-semana-da-conciliacao-e-execucao","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2021\/09\/23\/trt-rn-movimenta-mais-de-10-milhoes-e-e-destaque-nacional-na-semana-da-conciliacao-e-execucao\/","title":{"rendered":"TRT-RN movimenta mais de 10 milh\u00f5es e \u00e9 destaque nacional na Semana da Concilia\u00e7\u00e3o e Execu\u00e7\u00e3o"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/03\/cartorio-acessorio-acordo-aplicacao1.png\" alt=\"\" class=\"wp-image-7096\" width=\"462\" height=\"347\"\/><figcaption>Ilustrativa<\/figcaption><\/figure><\/div>\n\n\n\n<p>e Execu\u00e7\u00e3o Trabalhista, entre os Tribunais de pequeno porte. A informa\u00e7\u00e3o foi divulgada pelo Tribunal Superior do Trabalho (TST) em sua p\u00e1gina na internet que est\u00e1 acompanhando os resultados da Semana em tempo real.<\/p>\n\n\n\n<p>Entre a segunda-feira (20) e a quarta-feira (22), o TRT-RN movimentou mais de 10 milh\u00f5es de reais entre acordos, leil\u00e3o de bens penhorados para pagamento de processos trabalhistas, alvar\u00e1s liberados, precat\u00f3rios e arrecada\u00e7\u00f5es. O resultado garantiu o primeiro lugar para o TRT-RN como o Tribunal de pequeno porte que mais est\u00e1 executando no pa\u00eds.<\/p>\n\n\n\n<p>No per\u00edodo, houve 326 audi\u00eancias, 206 acordos e o atendimento a 868 pessoas, na capital e interior do Rio Grande do Norte.<\/p>\n\n\n\n<p>Magistrados e servidores do TRT-RN realizaram concilia\u00e7\u00f5es no 1\u00ba grau na ordem de R$ 5.447.568,34. Houve, nas datas, uma arrecada\u00e7\u00e3o para a Previd\u00eancia Social de R$ 462.542,49, al\u00e9m de R$ 160.602,92 em recolhimento fiscal e custas processuais.<\/p>\n\n\n\n<p>A mobiliza\u00e7\u00e3o no TRT-RN j\u00e1 garantiu a libera\u00e7\u00e3o de 96 alvar\u00e1s, que geraram pagamentos no valor de R$ 646.492,50. Com rela\u00e7\u00e3o aos alvar\u00e1s, ocorreu uma arrecada\u00e7\u00e3o previdenci\u00e1ria de R$ 43.246,96 e recolhimento fiscal e custas na ordem de R$ 18.393,68.<\/p><div class=\"tkwax6a03f1914c76e\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.tkwax6a03f1914c76e {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.tkwax6a03f1914c76e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.tkwax6a03f1914c76e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.tkwax6a03f1914c76e {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.tkwax6a03f1914c76e {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.tkwax6a03f1914c76e {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"yarqf6a03f1914c751\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.yarqf6a03f1914c751 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.yarqf6a03f1914c751 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.yarqf6a03f1914c751 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.yarqf6a03f1914c751 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.yarqf6a03f1914c751 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.yarqf6a03f1914c751 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p><strong>Leil\u00e3o<\/strong><\/p>\n\n\n\n<p>Na manh\u00e3 desta quarta-feira (22), a equipe da Divis\u00e3o de Intelig\u00eancia do TRT-RN realizou o 3\u00ba leil\u00e3o ordin\u00e1rio de 2021, na modalidade virtual, dentro da programa\u00e7\u00e3o da Semana Nacional da Concilia\u00e7\u00e3o e Execu\u00e7\u00e3o.<\/p>\n\n\n\n<p>Foram ofertados 46 lotes de bens m\u00f3veis, im\u00f3veis, ve\u00edculos, terrenos, equipamentos industriais e eletrodom\u00e9sticos, al\u00e9m de um barco timoneiro.<\/p>\n\n\n\n<p>Ao final do leil\u00e3o, houve a arremata\u00e7\u00e3o de 21 lotes, um deles com 47 lances, que garantiram uma arrecada\u00e7\u00e3o total de R$ 3.258.399,95.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>e Execu\u00e7\u00e3o Trabalhista, entre os Tribunais de pequeno porte. A informa\u00e7\u00e3o foi divulgada pelo Tribunal Superior do Trabalho (TST) em sua p\u00e1gina na internet que est\u00e1 acompanhando os resultados da Semana em tempo real. Entre a segunda-feira (20) e a quarta-feira (22), o TRT-RN movimentou mais de 10 milh\u00f5es de reais entre acordos, leil\u00e3o de<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2021\/09\/23\/trt-rn-movimenta-mais-de-10-milhoes-e-e-destaque-nacional-na-semana-da-conciliacao-e-execucao\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21776"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21776"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21776\/revisions"}],"predecessor-version":[{"id":21777,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21776\/revisions\/21777"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}