{"id":21634,"date":"2021-09-16T11:00:00","date_gmt":"2021-09-16T14:00:00","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=21634"},"modified":"2021-09-16T10:55:12","modified_gmt":"2021-09-16T13:55:12","slug":"camara-aprova-codigo-eleitoral-com-quarentena-para-juizes-e-policiais-a-partir-de-2026","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2021\/09\/16\/camara-aprova-codigo-eleitoral-com-quarentena-para-juizes-e-policiais-a-partir-de-2026\/","title":{"rendered":"C\u00e2mara aprova C\u00f3digo Eleitoral com quarentena para ju\u00edzes e policiais a partir de 2026"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>A C\u00e2mara dos Deputados concluiu, na madrugada desta quinta-feira, 16, a vota\u00e7\u00e3o do novo C\u00f3digo Eleitoral (PLP 112\/21). Aprovado na forma do substitutivo da relatora, deputada Margarete Coelho, o texto ser\u00e1 analisado ainda pelo Senado.<\/p>\n\n\n\n<p>O projeto consolida, em um \u00fanico texto, toda a legisla\u00e7\u00e3o eleitoral e temas de resolu\u00e7\u00f5es do TSE. Na principal vota\u00e7\u00e3o desta quarta-feira, 15, o plen\u00e1rio da C\u00e2mara retomou o tema da quarentena, que ser\u00e1 exigida de certas categorias para poderem disputar as elei\u00e7\u00f5es.<\/p>\n\n\n\n<p>Por 273 votos a 211, os deputados aprovaram emenda exigindo o desligamento de seu cargo, quatro anos antes do pleito, para ju\u00edzes, membros do Minist\u00e9rio P\u00fablico, policiais federais, rodovi\u00e1rios federais, policiais civis, guardas municipais, militares e policiais militares.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"660\" height=\"360\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/01\/plenario-camara-07032019171532185.jpeg\" alt=\"\" class=\"wp-image-5407\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/01\/plenario-camara-07032019171532185.jpeg 660w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/01\/plenario-camara-07032019171532185-300x164.jpeg 300w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><figcaption>Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p><br>Na semana passada, o plen\u00e1rio havia aprovado destaque do PSL que retirou do texto da relatora uma quarentena de cinco anos para ju\u00edzes e membros do Minist\u00e9rio P\u00fablico. Naquela vota\u00e7\u00e3o, 254 deputados opinaram por manter a quarentena, mas eram necess\u00e1rios 257 votos. Para manter a isonomia, tamb\u00e9m haviam sido aprovados outros destaques retirando a exig\u00eancia para as demais categorias.<\/p>\n\n\n\n<p>J\u00e1 a emenda aprovada nesta quarta-feira, assinada pelo deputado Cac\u00e1 Le\u00e3o e outros l\u00edderes partid\u00e1rios, prev\u00ea que ju\u00edzes e membros do Minist\u00e9rio P\u00fablico ter\u00e3o de se afastar definitivamente de seus cargos e fun\u00e7\u00f5es quatro anos antes do pleito. De igual forma, a norma valer\u00e1 para policiais federais, rodovi\u00e1rios federais, policiais civis e guardas municipais.<\/p>\n\n\n\n<p>Quanto a militares e policiais militares, os quatro anos dever\u00e3o ser anteriores ao come\u00e7o do per\u00edodo de escolha dos candidatos e das coliga\u00e7\u00f5es previsto para o ano eleitoral, que come\u00e7a em 20 de julho.<\/p>\n\n\n\n<p>Entretanto, at\u00e9 as elei\u00e7\u00f5es de 2026 vale o afastamento pela regra geral, em 2 de abril do ano eleitoral.<\/p>\n\n\n\n<p>&#8220;Quando a Constitui\u00e7\u00e3o veda a filia\u00e7\u00e3o partid\u00e1ria, de uma forma ou de outra abre uma fenda para que haja, realmente, limita\u00e7\u00f5es de direitos pol\u00edticos dessas categorias&#8221;, declarou a relatora.<\/p>\n\n\n\n<p>Ren\u00fancia<\/p><div class=\"hrlck6a03fc4375d87\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.hrlck6a03fc4375d87 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.hrlck6a03fc4375d87 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.hrlck6a03fc4375d87 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.hrlck6a03fc4375d87 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.hrlck6a03fc4375d87 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.hrlck6a03fc4375d87 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"hhhie6a03fc4375d71\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.hhhie6a03fc4375d71 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.hhhie6a03fc4375d71 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.hhhie6a03fc4375d71 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.hhhie6a03fc4375d71 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.hhhie6a03fc4375d71 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.hhhie6a03fc4375d71 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>Ainda em rela\u00e7\u00e3o \u00e0s situa\u00e7\u00f5es de inelegibilidade, emenda do deputado Danilo Cabral aprovada na semana passada manteve na lei o impedimento para aqueles que renunciaram no momento de abertura de processo de perda de mandato por infring\u00eancia a dispositivos constitucionais. A inelegibilidade vale para as elei\u00e7\u00f5es realizadas desde a ren\u00fancia e at\u00e9 oito anos ap\u00f3s o t\u00e9rmino da legislatura.<\/p>\n\n\n\n<p>Esse caso estava inicialmente de fora do texto da relatora.<\/p>\n\n\n\n<p>Improbidade administrativa<\/p>\n\n\n\n<p>Entretanto, outras situa\u00e7\u00f5es de inelegibilidade ser\u00e3o extintas, como a que impedia a candidatura de dirigentes n\u00e3o exonerados de responsabilidades pela liquida\u00e7\u00e3o judicial ou extrajudicial de institui\u00e7\u00f5es financeiras.<\/p>\n\n\n\n<p>Quanto aos que podem ser ineleg\u00edveis por terem sido exclu\u00eddos do exerc\u00edcio da profiss\u00e3o por infra\u00e7\u00e3o \u00e9tico-profissional ou demitidos do servi\u00e7o p\u00fablico por processo administrativo ou judicial, a restri\u00e7\u00e3o ser\u00e1 aplicada apenas se o motivo comprometer a moralidade para o exerc\u00edcio de mandatos eletivos.<\/p>\n\n\n\n<p>Para os que tiverem suas contas rejeitadas por ato doloso de improbidade administrativa em decis\u00e3o irrecorr\u00edvel, o texto prev\u00ea que a Justi\u00e7a Eleitoral, para reconhecer a inelegibilidade, n\u00e3o poder\u00e1 se basear em fatos que tenham sido objeto de procedimento preparat\u00f3rio ou inqu\u00e9rito civil arquivados ou de a\u00e7\u00e3o de improbidade extinta sem resolu\u00e7\u00e3o de m\u00e9rito, rejeitada com liminar, julgada improcedente ou julgada procedente somente em fun\u00e7\u00e3o de ato culposo.<\/p>\n\n\n\n<p>No caso de condena\u00e7\u00f5es transitadas em julgado ou em segunda inst\u00e2ncia, o texto aprovado mant\u00e9m a lista atual de crimes que implicam inelegibilidade, acrescentando aqueles contra a ordem tribut\u00e1ria, contra a economia e as rela\u00e7\u00f5es de consumo e contra o Estado Democr\u00e1tico de Direito.<\/p>\n\n\n\n<p>No entanto, o per\u00edodo no qual a pessoa n\u00e3o poder\u00e1 se candidatar passa a contar da condena\u00e7\u00e3o pelo crime e n\u00e3o mais a partir do fim do cumprimento da pena.<\/p>\n\n\n\n<p>Contagem inversa valer\u00e1 para o pol\u00edtico condenado a perda de mandato, para o qual os oito anos de inelegibilidade contar\u00e3o a partir da decis\u00e3o e n\u00e3o mais a partir do t\u00e9rmino do mandato, como \u00e9 hoje.<\/p>\n\n\n\n<p>Migalhas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara dos Deputados concluiu, na madrugada desta quinta-feira, 16, a vota\u00e7\u00e3o do novo C\u00f3digo Eleitoral (PLP 112\/21). Aprovado na forma do substitutivo da relatora, deputada Margarete Coelho, o texto ser\u00e1 analisado ainda pelo Senado. O projeto consolida, em um \u00fanico texto, toda a legisla\u00e7\u00e3o eleitoral e temas de resolu\u00e7\u00f5es do TSE. Na principal vota\u00e7\u00e3o<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2021\/09\/16\/camara-aprova-codigo-eleitoral-com-quarentena-para-juizes-e-policiais-a-partir-de-2026\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":21493,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21634"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21634"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21634\/revisions"}],"predecessor-version":[{"id":21635,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21634\/revisions\/21635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/21493"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}