{"id":16347,"date":"2021-01-29T10:46:21","date_gmt":"2021-01-29T13:46:21","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=16347"},"modified":"2021-01-30T14:47:15","modified_gmt":"2021-01-30T17:47:15","slug":"fernando-mineiro-e-diplomado-pelo-tre-rn-e-assumira-como-deputado-federal-no-lugar-de-beto-rosado","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2021\/01\/29\/fernando-mineiro-e-diplomado-pelo-tre-rn-e-assumira-como-deputado-federal-no-lugar-de-beto-rosado\/","title":{"rendered":"Fernando Mineiro \u00e9 diplomado pelo TRE-RN e assumir\u00e1 como deputado federal no lugar de Beto Rosado"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"489\" height=\"344\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2021\/01\/Captura-de-Tela-2021-01-29-a\u0300s-10.39.58.png\" alt=\"\" class=\"wp-image-16348\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2021\/01\/Captura-de-Tela-2021-01-29-a\u0300s-10.39.58.png 489w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2021\/01\/Captura-de-Tela-2021-01-29-a\u0300s-10.39.58-300x211.png 300w\" sizes=\"(max-width: 489px) 100vw, 489px\" \/><figcaption>Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>Fernando Mineiro (PT) recebeu na manh\u00e3 desta sexta-feira, 29, o diploma para o cargo de deputado federal emitido pelo Tribunal Regional Eleitoral (TRE-RN), ap\u00f3s a retotaliza\u00e7\u00e3o de votos com a anula\u00e7\u00e3o do registro de candidatura de Kericles Alves, o Kerinho, de forma que pelo novo quociente eleitoral Beto Rosado (PP) deixa o cargo para o candidato petista.<\/p>\n\n\n\n<p>A expectativa agora \u00e9 da posse de Mineiro na C\u00e2mara que deve ocorrer no in\u00edcio de fevereiro com o retorno das atividades legislativas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>RELEMBRE O CASO<\/p>\n\n\n\n<p>Nesta sexta-feira (22), a Corte do Tribunal Regional Eleitoral do Rio Grande do Norte (TRE-RN), indeferiu o pedido de registro de candidatura de Kericlis Alves Ribeiro, conhecido como Kerinho, nas Elei\u00e7\u00f5es de 2018.<\/p>\n\n\n\n<p>Com a decis\u00e3o, os votos conferidos a Kerinho no pleito foram tornados nulos e foi determinado o rec\u00e1lculo do quociente eleitoral para o cargo de deputado federal.<\/p><div class=\"fhvab6a04dfae62ddf\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.fhvab6a04dfae62ddf {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.fhvab6a04dfae62ddf {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.fhvab6a04dfae62ddf {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.fhvab6a04dfae62ddf {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.fhvab6a04dfae62ddf {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.fhvab6a04dfae62ddf {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"bliys6a04dfae62dc2\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.bliys6a04dfae62dc2 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.bliys6a04dfae62dc2 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.bliys6a04dfae62dc2 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.bliys6a04dfae62dc2 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.bliys6a04dfae62dc2 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.bliys6a04dfae62dc2 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>O relator do processo, juiz Ricardo Tinoco, foi acompanhado pelo Desembargador Ibanez Monteiro e pelo Juiz Federal Carlos Wagner para formar maioria pelo indeferimento. Foram vencidos os ju\u00edzes eleitorais Adriana Magalh\u00e3es e Fernando Jales. O juiz Geraldo Mota declarou impedimento no processo.<\/p>\n\n\n\n<p>A maioria entendeu que Kerinho permaneceu vinculado a um cargo comissionado dentro de per\u00edodo vedado para pretensos candidatos. &#8220;O requerente n\u00e3o atendeu \u00e0 exig\u00eancia de desincompatibiliza\u00e7\u00e3o, em virtude de n\u00e3o ter se exonerado do cargo de confian\u00e7a que ocupava no Munic\u00edpio de Monte Alegre, incidindo assim na causa de inelegibilidade do art. 1\u00ba, inciso 2 al\u00ednea &#8220;l&#8221; e do inciso 6, da Lei Complementar n\u00ba 64\/90&#8243;, apontou Ricardo Tinoco.<\/p>\n\n\n\n<p>&#8220;Ele deveria comprovar a devida exonera\u00e7\u00e3o, pois estava em um cargo comissionado. N\u00e3o \u00e9 suficiente para comprovar a exonera\u00e7\u00e3o um mero requerimento&#8221;, explicou o Juiz Federal Carlos Wagner.<\/p>\n\n\n\n<p>&#8220;Por consequ\u00eancia, torno nulos os votos a ele conferidos para determinar que se recalcule os quocientes previstos nos artigos 106 e 107 do C\u00f3digo Eleitoral em rela\u00e7\u00e3o ao cargo de deputado federal, procedendo-se \u00e0s medidas cab\u00edveis decorrentes da retotaliza\u00e7\u00e3o&#8221;, concluiu o relator em seu voto.<\/p>\n\n\n\n<p>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fernando Mineiro (PT) recebeu na manh\u00e3 desta sexta-feira, 29, o diploma para o cargo de deputado federal emitido pelo Tribunal Regional Eleitoral (TRE-RN), ap\u00f3s a retotaliza\u00e7\u00e3o de votos com a anula\u00e7\u00e3o do registro de candidatura de Kericles Alves, o Kerinho, de forma que pelo novo quociente eleitoral Beto Rosado (PP) deixa o cargo para o<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2021\/01\/29\/fernando-mineiro-e-diplomado-pelo-tre-rn-e-assumira-como-deputado-federal-no-lugar-de-beto-rosado\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":16348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16347"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16347"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16347\/revisions"}],"predecessor-version":[{"id":16349,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16347\/revisions\/16349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/16348"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}