{"id":15123,"date":"2020-12-07T13:43:19","date_gmt":"2020-12-07T16:43:19","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=15123"},"modified":"2020-12-07T11:15:19","modified_gmt":"2020-12-07T14:15:19","slug":"defensoria-publica-esta-com-inscricoes-abertas-para-estagiarios-de-direito-no-rn","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2020\/12\/07\/defensoria-publica-esta-com-inscricoes-abertas-para-estagiarios-de-direito-no-rn\/","title":{"rendered":"Defensoria P\u00fablica est\u00e1 com inscri\u00e7\u00f5es abertas para estagi\u00e1rios de Direito no RN"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/12\/3-1024x1024.jpg\" alt=\"\" class=\"wp-image-15124\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/12\/3-1024x1024.jpg 1024w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/12\/3-300x300.jpg 300w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/12\/3-150x150.jpg 150w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/12\/3-768x768.jpg 768w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/12\/3.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Defensoria P\u00fablica do Estado do Rio Grande do Norte (DPE\/RN) abriu a XIII Sele\u00e7\u00e3o Simplificada para estagi\u00e1rios do curso de Direito. O processo seletivo ser\u00e1 destinado a forma\u00e7\u00e3o de cadastro reserva para atua\u00e7\u00e3o nos n\u00facleos de Cear\u00e1-Mirim, Currais Novos, Jo\u00e3o C\u00e2mara, Maca\u00edba, N\u00edsia Floresta e Pau dos Ferros. O edital completo est\u00e1 dispon\u00edvel\u00a0<a href=\"https:\/\/defensoria.rn.def.br\/pagina\/xiii-selecao-simplificada-para-estagiarios-de-direito\"><strong>AQUI<\/strong><\/a>. As inscri\u00e7\u00f5es podem ser feitas gratuitamente atrav\u00e9s de e-mail entre os dias 07 e 16 de dezembro.<\/p>\n\n\n\n<p>Para se inscrever, o candidato dever\u00e1, obrigatoriamente, enviar no e-mail, digitalizado e em formato PDF seu formul\u00e1rio de inscri\u00e7\u00e3o preenchido, c\u00f3pia simples de documento de identifica\u00e7\u00e3o e CPF, al\u00e9m de hist\u00f3rico escolar emitido pela Institui\u00e7\u00e3o de Ensino Superior, devidamente atualizado e assinado pela Coordena\u00e7\u00e3o de Ensino ou com autentica\u00e7\u00e3o eletr\u00f4nica. A sele\u00e7\u00e3o consistir\u00e1 em uma avalia\u00e7\u00e3o das notas do candidato constantes no seu hist\u00f3rico universit\u00e1rio, considerando o IRA (\u00edndice de rendimento acad\u00eamico) ou outro indicador similar. O candidato poder\u00e1 concorrer em mais de um N\u00facleo, devendo enviar mensagem de inscri\u00e7\u00e3o espec\u00edfica para o e-mail de cada N\u00facleo pretendido com a documenta\u00e7\u00e3o completa.<\/p>\n\n\n\n<p>Os candidatos que pretendem concorrer \u00e0s vagas reservadas \u00e0s pessoas com defici\u00eancia dever\u00e3o declarar-se como tal no espa\u00e7o reservado no formul\u00e1rio de inscri\u00e7\u00e3o, bem como enviar, no e-mail da inscri\u00e7\u00e3o, os documentos previstos no Art.15 e laudo m\u00e9dico original ou c\u00f3pia simples de acordo com o Edital 24\/2020. Ao todo, 10% das vagas ser\u00e3o destinadas para pessoas com defici\u00eancia que atendam \u00e0s exig\u00eancias expressas no Edital.<\/p>\n\n\n\n<p>Os candidatos selecionados ter\u00e3o um contrato de um ano prorrog\u00e1vel por igual per\u00edodo. Os estagi\u00e1rios da Defensoria P\u00fablica do Rio Grande do Norte atuam no turno matutino com carga hor\u00e1ria de 30h semanais e recebem uma bolsa mensal de um sal\u00e1rio m\u00ednimo mais aux\u00edlio-transporte, n\u00e3o originando nenhum v\u00ednculo empregat\u00edcio com a institui\u00e7\u00e3o. O resultado da sele\u00e7\u00e3o ser\u00e1 divulgado no site da Defensoria P\u00fablica do Estado e no Di\u00e1rio Oficial do Estado do Rio Grande do Norte.<\/p>\n\n\n\n<p>SERVI\u00c7O:<\/p>\n\n\n\n<p>XIII SELE\u00c7\u00c3O SIMPLIFICADA DE ESTAGI\u00c1RIOS DE DIREITO DA DPE\/RN<\/p>\n\n\n\n<p>INSCRI\u00c7\u00d5ES: 07 A 16 DE DEZEMBRO DE 2020<\/p><div class=\"jxhuf6a97c25349e07\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.jxhuf6a97c25349e07 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.jxhuf6a97c25349e07 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.jxhuf6a97c25349e07 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.jxhuf6a97c25349e07 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.jxhuf6a97c25349e07 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.jxhuf6a97c25349e07 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"rlhtk6a97c25349df0\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.rlhtk6a97c25349df0 {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.rlhtk6a97c25349df0 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.rlhtk6a97c25349df0 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.rlhtk6a97c25349df0 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.rlhtk6a97c25349df0 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.rlhtk6a97c25349df0 {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>E-MAILS:<\/p>\n\n\n\n<p><a href=\"mailto:cearamirim@dpe.rn.def.br\">cearamirim@dpe.rn.def.br<\/a>;<\/p>\n\n\n\n<p>curraisnovos<a href=\"mailto:ceara-mirim@dpe.rn.def.br\">@dpe.rn.def.br<\/a>;<\/p>\n\n\n\n<p><a href=\"mailto:joaocamara@dpe.rn.def.br\">joaocamara@dpe.rn.def.br<\/a>;<\/p>\n\n\n\n<p>macaiba<a href=\"mailto:ceara-mirim@dpe.rn.def.br\">@dpe.rn.def.br<\/a>;<\/p>\n\n\n\n<p><a href=\"mailto:nisiafloresta@dpe.rn.def.br\">nisiafloresta@dpe.rn.def.br<\/a><\/p>\n\n\n\n<p><a href=\"mailto:paudosferros@dpe.rn.def.br\">paudosferros@dpe.rn.def.br<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Defensoria P\u00fablica do Estado do Rio Grande do Norte (DPE\/RN) abriu a XIII Sele\u00e7\u00e3o Simplificada para estagi\u00e1rios do curso de Direito. O processo seletivo ser\u00e1 destinado a forma\u00e7\u00e3o de cadastro reserva para atua\u00e7\u00e3o nos n\u00facleos de Cear\u00e1-Mirim, Currais Novos, Jo\u00e3o C\u00e2mara, Maca\u00edba, N\u00edsia Floresta e Pau dos Ferros. O edital completo est\u00e1 dispon\u00edvel\u00a0AQUI. As<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2020\/12\/07\/defensoria-publica-esta-com-inscricoes-abertas-para-estagiarios-de-direito-no-rn\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":15124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/15123"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=15123"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/15123\/revisions"}],"predecessor-version":[{"id":15125,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/15123\/revisions\/15125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/15124"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=15123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=15123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=15123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}