{"id":10370,"date":"2020-06-08T14:57:20","date_gmt":"2020-06-08T17:57:20","guid":{"rendered":"https:\/\/justicapotiguar.com.br\/?p=10370"},"modified":"2020-06-08T11:59:14","modified_gmt":"2020-06-08T14:59:14","slug":"a-venda-casada-na-jurisprudencia-do-stj","status":"publish","type":"post","link":"https:\/\/justicapotiguar.com.br\/index.php\/2020\/06\/08\/a-venda-casada-na-jurisprudencia-do-stj\/","title":{"rendered":"A &#8220;venda casada&#8221; na jurisprud\u00eancia do STJ"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"739\" height=\"415\" src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/06\/images-38.jpeg\" alt=\"\" class=\"wp-image-10371\" srcset=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/06\/images-38.jpeg 739w, https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2020\/06\/images-38-300x168.jpeg 300w\" sizes=\"(max-width: 739px) 100vw, 739px\" \/><figcaption>Ilustrativa<\/figcaption><\/figure>\n\n\n\n<p><strong>Por Rodrigo Leite<\/strong><\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;No seu&nbsp;<strong>art. 39,<\/strong>&nbsp;o C\u00f3digo de Defesa do Consumidor prev\u00ea&nbsp;<strong>um rol exemplificativo<\/strong>&nbsp;das chamadas&nbsp;<strong>pr\u00e1ticas abusivas<\/strong>, condutas vedadas no mercado de consumo. Entre elas est\u00e1 a denominada&nbsp;<em>\u201cvenda casada\u201d<\/em>&nbsp;que ocorre quando o fornecedor&nbsp;<strong>condiciona a aquisi\u00e7\u00e3o de produto ou de servi\u00e7o ao fornecimento de outro produto ou servi\u00e7o<\/strong>, sem conferir liberdade ou alternativas ao consumidor. Eis a reda\u00e7\u00e3o do art. 39, I, do CDC:<\/p>\n\n\n\n<p><em>\u201cArt. 39. \u00c9 vedado ao fornecedor de produtos ou servi\u00e7os, dentre outras pr\u00e1ticas abusivas:&nbsp;&nbsp;<\/em><\/p>\n\n\n\n<p><em>I &#8211; condicionar o fornecimento de produto ou de servi\u00e7o ao fornecimento de outro produto ou servi\u00e7o, bem como, sem justa causa, a limites quantitativos;\u201d<\/em><\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;A venda casada representa, como dito, uma pr\u00e1tica abusiva de obrigar o consumidor a adquirir um produto ou servi\u00e7o atrelado a outro ofertado pelo fornecedor. \u00c9 a venda ou disponibiliza\u00e7\u00e3o associada ou vinculada (\u201carranjo de amarra\u00e7\u00e3o\u201d) \u00e0 aquisi\u00e7\u00e3o de outro produto ou servi\u00e7o, sem se conferir alternativa ou op\u00e7\u00e3o livre ao adquirente.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;A denominada venda casada (<em>tying arrangement<\/em>) representa uma viola\u00e7\u00e3o \u00e0 boa-f\u00e9 objetiva e consiste no preju\u00edzo \u00e0 liberdade de escolha do consumidor decorrente do condicionamento, subordina\u00e7\u00e3o e vincula\u00e7\u00e3o da aquisi\u00e7\u00e3o de um produto ou servi\u00e7o (principal &#8211; &#8220;tying&#8221;) \u00e0 concomitante aquisi\u00e7\u00e3o de outro (secund\u00e1rio &#8211; &#8220;tied&#8221;), quando o prop\u00f3sito do consumidor \u00e9, unicamente, o de obter o produto ou servi\u00e7o principal \u2013 ver voto da Min. Nancy Andrighi no emblem\u00e1tico&nbsp;<strong>REsp 1737428\/RS<\/strong>, julgado em 12\/03\/2019.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;De fato, o direito \u00e0 informa\u00e7\u00e3o derivado da boa-f\u00e9 objetiva deve permitir ao consumidor avaliar de modo livre, consciente e com lucidez a conveni\u00eancia (ou n\u00e3o) de sua ades\u00e3o ao respectivo contrato. A venda casada implica, por sua vez, numa imposi\u00e7\u00e3o unilateral consistente na inclus\u00e3o de servi\u00e7o n\u00e3o solicitado ou com informa\u00e7\u00f5es insuficientes ou inadequadas sobre um produto ou servi\u00e7o.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Para o STJ, a venda casada ocorre em virtude do condicionamento a uma \u00fanica escolha, a apenas uma alternativa, j\u00e1 que n\u00e3o \u00e9 conferido ao consumidor usufruir de outro produto sen\u00e3o aquele alienado pelo fornecedor (<strong>REsp 1331948\/SP<\/strong>).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Podemos citar, como exemplo, comuns no dia a dia: i) a venda de telefonia atrelada ao plano de internet, ii) o fornecimento de um cart\u00e3o de cr\u00e9dito atrelada a de um seguro, iii) a compra e venda de bem im\u00f3vel vinculada ao contrato de seguro fornecido pelo banco, iv) impedir o consumidor de ingressar no cinema com produtos (refrigerantes, \u00e1gua, pipoca ou chocolates, por exemplo) adquiridos fora do estabelecimento de reprodu\u00e7\u00e3o cinematogr\u00e1fica.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Segundo o STJ, h\u00e1 venda casada na imposi\u00e7\u00e3o aos consumidores de contrata\u00e7\u00e3o de outros produtos para a obten\u00e7\u00e3o de empr\u00e9stimo e abertura de conta-corrente (<strong>AgInt no REsp 1336939\/RS<\/strong>, Rel. Ministro Luis Felipe Salom\u00e3o, Quarta Turma, julgado em 17\/12\/2019, DJe 19\/05\/2020).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Tamb\u00e9m ocorre venda casada na previs\u00e3o de cancelamento unilateral da passagem de volta, em raz\u00e3o do n\u00e3o comparecimento para embarque no trecho de ida (no show). Referida pr\u00e1tica configura &#8220;venda casada&#8221;, pois condiciona o fornecimento do servi\u00e7o de transporte a\u00e9reo do &#8220;trecho de volta&#8221; \u00e0 utiliza\u00e7\u00e3o do &#8220;trecho de ida&#8221; (CDC, art. 39, I).\u201d (<strong>REsp 1699780\/SP<\/strong>, Rel. Ministro Marco Aur\u00e9lio Bellizze, Terceira Turma, julgado em 11\/09\/2018, DJe 17\/09\/2018). Entende-se que o condicionamento, para a utiliza\u00e7\u00e3o do servi\u00e7o, o pressuposto criado para atender apenas o interesse da fornecedora, no caso, o embarque no trecho de ida, caracteriza-se a indesej\u00e1vel pr\u00e1tica de&nbsp;venda casada.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;O STJ considera ainda que \u201cao compelir o consumidor a comprar dentro do pr\u00f3prio cinema todo e qualquer produto aliment\u00edcio, o estabelecimento dissimula uma venda casada (art. 39, I, do CDC), limitando a liberdade de escolha do consumidor (art. 6\u00ba, II, do CDC), o que revela pr\u00e1tica abusiva.\u201d (<strong>REsp 1331948\/SP<\/strong>, Rel. Ministro Ricardo Villas B\u00f4as Cueva, Terceira Turma, julgado em 14\/06\/2016, DJe 05\/09\/2016).<\/p><div class=\"ixptf6a985f8fd5358\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/mobile-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.ixptf6a985f8fd5358 {\r\ntext-align: center;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.ixptf6a985f8fd5358 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ixptf6a985f8fd5358 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ixptf6a985f8fd5358 {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ixptf6a985f8fd5358 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ixptf6a985f8fd5358 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"krisl6a985f8fd533a\" ><!--<a href=\"https:\/\/bit.ly\/3QdrqTZ\" target=\"_blank\">\n<img src=\"https:\/\/justicapotiguar.com.br\/wp-content\/uploads\/2023\/09\/desktop-geral.gif\"\/><a\/>--><\/div><style type=\"text\/css\">\r\n.krisl6a985f8fd533a {\r\ntext-align: center;\nmargin-bottom: 1em;\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.krisl6a985f8fd533a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.krisl6a985f8fd533a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.krisl6a985f8fd533a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.krisl6a985f8fd533a {\r\ndisplay: none;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.krisl6a985f8fd533a {\r\ndisplay: none;\r\n}\r\n}\r\n<\/style>\r\n\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;No emblem\u00e1tico&nbsp;<strong>REsp 1737428\/RS<\/strong>, Rel. Ministra Nancy Andrighi, Terceira Turma, julgado em 12\/03\/2019, DJe 15\/03\/2019), o STJ entendeu que ao submeter os ingressos \u00e0 venda terceirizada em meio virtual (da internet), deve-se oferecer ao consumidor diversas op\u00e7\u00f5es de compra em diversos s\u00edtios eletr\u00f4nicos, caso contr\u00e1rio, a liberdade dos consumidores de escolha da intermediadora da compra \u00e9 cerceada, limitada unicamente aos servi\u00e7os oferecidos pela recorrida, de modo a ficar configurada a venda casada, nos termos do art. 39, I e IX, do CDC.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Nos contratos banc\u00e1rios em geral, o consumidor n\u00e3o pode ser compelido a contratar seguro com a institui\u00e7\u00e3o financeira ou com seguradora por ela indicada. Assim, representa \u201cvenda casada\u201d obrigar o consumidor a contratar seguro de prote\u00e7\u00e3o financeira (<strong>REsp 1639259\/SP<\/strong>, Rel. Ministro Paulo de Tarso Sanseverino, Segunda Se\u00e7\u00e3o, julgado em 12\/12\/2018, DJe 17\/12\/2018).<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Tamb\u00e9m haveria venda casada, se para adquirir\/comprar um rel\u00f3gio, fosse necess\u00e1rio que o consumidor comprasse tamb\u00e9m 5 (cinco) produtos de uma marca de biscoitos \u2013&nbsp;<strong>REsp 1558086\/SP<\/strong>, Rel. Ministro Humberto Martins, Segunda Turma, julgado em 10\/03\/2016, DJe 15\/04\/2016. Ocorrer\u00e1 venda casada se a empresa de telefonia imp\u00f5e a aquisi\u00e7\u00e3o de aparelho telef\u00f4nico aos consumidores que demonstrassem interesse em adquirir o servi\u00e7o de telefonia (<strong>REsp 1397870\/MG<\/strong>, Rel. Ministro Mauro Campbell Marques, Segunda Turma, julgado em 02\/12\/2014, DJe 10\/12\/2014)<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Por sua vez, o contrato de plano de pec\u00falio, celebrado com a finalidade de concretizar a filia\u00e7\u00e3o aos quadros de entidade aberta de previd\u00eancia complementar, constitui-se em requisito para a concess\u00e3o do empr\u00e9stimo ao interessado e, portanto, n\u00e3o se enquadra na veda\u00e7\u00e3o \u00e0 \u201cvenda casada\u201d de que trata o art. 39, inc. I, da Lei 8.078\/90 (<strong>AgInt no AREsp 576.000\/RJ<\/strong>, Rel. Ministro Antonio Carlos Ferreira, Quarta Turma, julgado em 04\/12\/2018, DJe 11\/12\/2018).<\/p>\n\n\n\n<p>Abra\u00e7o a todos!<\/p>\n\n\n\n<p><strong>Que receber informa\u00e7\u00f5es jur\u00eddicas gratuitas pelo celular?<\/strong>&nbsp;Informe nome e cidade para o&nbsp;<em>whatsapp<\/em>&nbsp;84-99431-2074. \u00c9 minha lista de transmiss\u00e3o.<\/p>\n\n\n\n<p><strong>Rodrigo Leite<\/strong><\/p>\n\n\n\n<p>Autor e coautor de 4 livros jur\u00eddicos (Juspodivm e Saraiva)<\/p>\n\n\n\n<p>Mestre em Direito Constitucional<\/p>\n\n\n\n<p>Assessor de Desembargador do TJRN<\/p>\n\n\n\n<p>Professor da P\u00f3s On-line de Civil da Rede Kroton-LFG<\/p>\n\n\n\n<p>Conteudista dos sites\u00a0<a rel=\"noreferrer noopener\" href=\"http:\/\/justicapotiguar.com.br\/\" target=\"_blank\">justicapotiguar.com.br<\/a>\u00a0(RN),\u00a0<a rel=\"noreferrer noopener\" href=\"http:\/\/novodireitocivil.com.br\/\" target=\"_blank\">novodireitocivil.com.br<\/a>\u00a0(BA),\u00a0<a rel=\"noreferrer noopener\" href=\"http:\/\/meusitejuridico.com.br\/\" target=\"_blank\">meusitejuridico.com.br<\/a>\u00a0(SP) e\u00a0<a rel=\"noreferrer noopener\" href=\"http:\/\/supremotv.com.br\/\" target=\"_blank\">supremotv.com.br<\/a>\u00a0(MG).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Rodrigo Leite &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;No seu&nbsp;art. 39,&nbsp;o C\u00f3digo de Defesa do Consumidor prev\u00ea&nbsp;um rol exemplificativo&nbsp;das chamadas&nbsp;pr\u00e1ticas abusivas, condutas vedadas no mercado de consumo. Entre elas est\u00e1 a denominada&nbsp;\u201cvenda casada\u201d&nbsp;que ocorre quando o fornecedor&nbsp;condiciona a aquisi\u00e7\u00e3o de produto ou de servi\u00e7o ao fornecimento de outro produto ou servi\u00e7o, sem conferir liberdade ou alternativas ao consumidor. Eis a<br \/><a class=\"more-link\" href=\"https:\/\/justicapotiguar.com.br\/index.php\/2020\/06\/08\/a-venda-casada-na-jurisprudencia-do-stj\/\">Mais&#8230;<\/a><\/p>\n","protected":false},"author":5,"featured_media":10371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10370"}],"collection":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10370"}],"version-history":[{"count":1,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10370\/revisions"}],"predecessor-version":[{"id":10372,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10370\/revisions\/10372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media\/10371"}],"wp:attachment":[{"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justicapotiguar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}